{"id":2136,"date":"2016-03-28T12:18:29","date_gmt":"2016-03-28T10:18:29","guid":{"rendered":"http:\/\/posicuarta.org\/cartasblog\/?p=2136"},"modified":"2016-03-28T12:18:29","modified_gmt":"2016-03-28T10:18:29","slug":"ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso","status":"publish","type":"post","link":"http:\/\/posicuarta.org\/cartasblog\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\/","title":{"rendered":"\u00a1Ahora es urgente parar el golpe de los jueces que est\u00e1 en curso!"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><strong><em>Manifiesto del 2\u00ba Encuentro Nacional de Di\u00e1logo y Acci\u00f3n Petista<\/em><\/strong><\/h3>\n<p style=\"text-align: justify;\">Reunido en S\u00e3o Paulo, en la sede nacional del PT, el 19 y 20 de marzo, el Encuentro Nacional de Di\u00e1logo y Acci\u00f3n Petista (*) llama a sus afiliados y simpatizantes, a todos y todas los militantes petistas, a los trabajadores y j\u00f3venes, a la acci\u00f3n inmediata para parar el golpe que est\u00e1 produci\u00e9ndose en el Brasil contra la democracia, la soberan\u00eda popular y nacional, contra los derechos sociales y de los trabajadores.<\/p>\n<p style=\"text-align: justify;\">El 18 de marzo, convocados por la CUT, el MST, la UNE, el PT y decenas de entidades m\u00e1s y organizaciones de lucha del pueblo trabajador y de la juventud, m\u00e1s de 1.300.000 manifestantes tomaron las calles de todo el pa\u00eds diciendo No al Golpe. Un golpe que tiene como instrumento la Operaci\u00f3n Lava Jato, que pretende instaurar un Estado policial de excepci\u00f3n, una dictadura del poder judicial.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Esta demostraci\u00f3n del 18 de marzo de resistencia contra el golpe y de voluntad de lucha para defender las conquistas democr\u00e1ticas y sociales conseguidas por nuestro pueblo tuvo un gran impacto en la situaci\u00f3n pol\u00edtica de la naci\u00f3n y anim\u00f3 a la militancia, creando una trinchera que estamos llamados a reforzar cada vez m\u00e1s y cada d\u00eda, pues la escalada golpista se acelera.<\/p>\n<p style=\"text-align: justify;\">As\u00ed, el mismo 18 de marzo por la noche el ministro Gilmar Mendes, del Supremo, en abierta complicidad con el juez Moro y con la oposici\u00f3n, suspendi\u00f3 la toma de posesi\u00f3n de Lula como ministro del gobierno Dilma, apostando por profundizar a\u00fan m\u00e1s la crisis para derribar al Gobierno.<\/p>\n<h4 style=\"text-align: justify;\"><strong>La corrupci\u00f3n es un pretexto<\/strong><\/h4>\n<p style=\"text-align: justify;\">El pretexto del combate contra la represi\u00f3n se ha convertido en la justificaci\u00f3n para \u201cdelaciones premiadas\u201d que obvian pruebas para condenar a objetivos seleccionados, para \u201ctrasladar por la fuerza\u201d ciudadanos a prestar declaraci\u00f3n, como sucedi\u00f3 con el ex presidente Lula, para encarcelamientos espectaculares y filtraciones selectivas de informaciones \u2013que deber\u00edan ser secreto de justicia\u2013 a alg\u00fan medio de comunicaci\u00f3n que participe en el golpe, como la red Globo, que lo promueve intoxicando a la poblaci\u00f3n con odio contra el PT.<\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 combate contra la corrupci\u00f3n es \u00e9se que permite que Eduardo Cunha, del PMDB, orqueste el proceso de impeachment contra la presidenta Dilma? \u00bfQu\u00e9 permite que A\u00e9cio Neves, citado por acusadores en varios casos de corrupci\u00f3n, siga con bravatas, posando como defensor de la \u00e9tica?<\/p>\n<h4 style=\"text-align: justify;\"><strong>Plan de emergencia<\/strong><\/h4>\n<p style=\"text-align: justify;\">La adopci\u00f3n de un Plan de Emergencia por el PT puso nerviosos a golpistas y empresarios. Porque ese plan podr\u00eda dar lugar a una inflexi\u00f3n en la pol\u00edtica econ\u00f3mica en relaci\u00f3n con el ajuste presupuestario que tanto da\u00f1o caus\u00f3 a la clase trabajadora y al pueblo pobre. El nombramiento de Lula por Dilma como ministro de la Presidencia, que ha despertado expectativas positivas de cambio en la pol\u00edtica del Gobierno, para los golpistas ha sido la se\u00f1al para tratar de encarcelar al l\u00edder hist\u00f3rico del PT y derribar como sea a la Presidenta elegida.<\/p>\n<p style=\"text-align: justify;\">Al efecto, los golpistas con toga han osado lo que nunca nadie os\u00f3 en este pa\u00eds, ni siquiera en los a\u00f1os sombr\u00edos de la dictadura militar: la divulgaci\u00f3n por el juez Moro de la grabaci\u00f3n ilegal de una conversaci\u00f3n de la Presidenta de la Rep\u00fablica con el ministro reci\u00e9n nombrado. Ese atropello inadmisible de la legalidad, cometido por un juez de primera instancia del estado de Curitiba, solo puede prosperar con la complicidad del Supremo Tribunal Federal.<\/p>\n<h4 style=\"text-align: justify;\"><strong>Es la patronal y el imperialismo<\/strong><\/h4>\n<p style=\"text-align: justify;\">La forma del golpe es una operaci\u00f3n jur\u00eddico-policial, articulada con la acci\u00f3n del PSDB y la mayor\u00eda del PMDB en el Congreso. Pero los intereses a los que el golpe sirve son los de quienes, dentro y fuera del Brasil, quieren entregar la riqueza de los yacimientos de Presal a las multinacionales, quieren privatizar las empresas estatales (sector el\u00e9ctrico, Petrobras, etc.), quieren liquidar los derechos laborales \u2013como indican los 55 proyectos de ley en el Congreso, desde la tercerizaci\u00f3n ilimitada hasta la anulaci\u00f3n de la CLT que da prevalencia a lo negociado sobre lo legislado\u2013 y destruir las organizaciones sindicales de lucha.<\/p>\n<p style=\"text-align: justify;\">El golpe sirve a los intereses de los que quieren liquidar programas sociales, entregar tierras ind\u00edgenas y comunidades negras al agronegocio e impedir cualquier reanudaci\u00f3n de la reforma agraria, para beneficio de los latifundios.<\/p>\n<p style=\"text-align: justify;\">No es casual que la escalada golpista incluya ataques a locales del PT, de la CUT, de la UNE y otras entidades de lucha de nuestro pueblo, o que la Polic\u00eda Militar invada la subsede del sindicato de metal\u00fargicos en Diadema y un teniente entre en la sede estatal del PT de S\u00e3o Paulo. Son acciones que buscan intimidar la resistencia organizada al golpe en curso.<\/p>\n<p style=\"text-align: justify;\">Detr\u00e1s del juez Moro, h\u00e9roe de los se\u00f1oritos reaccionarios de S\u00e3o Paulo, cuyos alegatos destilan prejuicios raciales y sociales de todo tipo y desprecian al pueblo pobre, con amplia cobertura de <em>O Globo<\/em> y de otros medios privados, est\u00e1 la FIESP (patronal de S\u00e3o Paulo) y otras entidades patronales, est\u00e1 el imperialismo de los Estados Unidos que quiere recuperar el terreno perdido en Am\u00e9rica Latina.<\/p>\n<p style=\"text-align: justify;\">Estamos en un momento crucial y decisivo, ya que el verdadero blanco de este golpe son las organizaciones construidas por la clase trabajadora y por los sectores explotados y oprimidos de nuestro pueblo. Por eso es criminal la pol\u00edtica de los que se llaman \u201cde izquierdas\u201d pero hacen del \u201cFuera Dilma y fuera el PT\u201d su bandera central, coloc\u00e1ndose objetivamente en el campo de la reacci\u00f3n proimperialista, al lado de la FIESP, de los reaccionarios y del juez Moro.<\/p>\n<h4 style=\"text-align: justify;\"><strong>Ganar todas las organizaciones<\/strong><\/h4>\n<p style=\"text-align: justify;\">Los militantes de Di\u00e1logo y Acci\u00f3n Petista (DAP) est\u00e1n llamados a tener un papel activo en la construcci\u00f3n de la m\u00e1s amplia unidad para detener el golpe en curso. Todav\u00eda hay tiempo, pues la fuerza demostrada en las manifestaciones del 18 de marzo puede y debe ampliarse. Las reuniones de base del DAP \u2013adem\u00e1s de discutir el programa de emergencia del PT\u2013 deben asumir esta tarea inmediatamente.<\/p>\n<p style=\"text-align: justify;\">Llamamos a todos los militantes de la causa del pueblo trabajador y de la democracia, petistas o no, a actuar juntos para ganar todas las organizaciones sindicales y populares para movilizar a sus bases contra el golpe. Y a partir de ah\u00ed, seg\u00fan el caso, organizar comit\u00e9s contra el golpe.<\/p>\n<p style=\"text-align: justify;\">En el campo y en la ciudad, es hora de ir a los centros de trabajo, barrios y pueblos, a las periferias de las regiones metropolitanas, para ayudar a nuestro pueblo a comprender la manipulaci\u00f3n a la que est\u00e1 siendo sometido por quienes le explotan y acuda a sumarse a la lucha contra el golpe.<\/p>\n<p style=\"text-align: justify;\">Para que la crisis tenga una salida positiva, la clave est\u00e1 en la movilizaci\u00f3n para detener el golpe y en la aplicaci\u00f3n inmediata por el gobierno Dilma del plan de emergencia del PT, no en la b\u00fasqueda ilusoria de acuerdos con una coalici\u00f3n que se ha desmoronado y con una oposici\u00f3n en torno del ajuste presupuestario que ataca derechos y promueve el desempleo.<\/p>\n<p style=\"text-align: justify;\">Manteng\u00e1monos alerta y preparados para la acci\u00f3n en cualquier momento, pues en este momento en que todo se decide los d\u00edas valen por semanas.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #993300; font-size: 12pt;\"><strong>\u00a1Es hora de parar el golpe de los jueces!<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #993300; font-size: 12pt;\"><strong>\u00a1En defensa de la democracia, de los derechos de los trabajadores y de la soberan\u00eda nacional!<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #993300; font-size: 12pt;\"><strong>\u00a1En defensa del PT y de las organizaciones de lucha de nuestro pueblo!<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Manifiesto del Encuentro: Reunido en S\u00e3o Paulo, en la sede nacional del PT, el 19 y 20 de marzo, el Encuentro Nacional de Di\u00e1logo y Acci\u00f3n Petista (*) llama a sus afiliados y simpatizantes, a todos y todas los militantes petistas, a los trabajadores y j\u00f3venes, a la acci\u00f3n inmediata para parar el golpe que est\u00e1 produci\u00e9ndose en el Brasil contra la democracia, la soberan\u00eda popular y nacional, contra los derechos sociales y de los trabajadores.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"aside","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[20,8,27],"tags":[617,106,108,109,621,619,618,620,107,622],"class_list":["post-2136","post","type-post","status-publish","format-aside","hentry","category-declaracion","category-internacional","category-iv-internacional","tag-accion-petista","tag-brasil","tag-cut","tag-dilma-rousseff","tag-eduardo-cunha","tag-gilmar-mendes","tag-juez-moro","tag-lula","tag-partido-de-los-trabajadores","tag-pmdb","post_format-post-format-aside"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Manifiesto del 2\u00ba Encuentro Nacional de Di\u00e1logo y Acci\u00f3n Petista (agrupamiento de militantes del PT impulsado por la secci\u00f3n de la Cuarta O Trabalho)\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"keywords\" content=\"acci\u00f3n petista,brasil,cut,dilma rousseff,eduardo cunha,gilmar mendes,juez moro,lula,partido de los trabajadores,pmdb,declaraci\u00f3n,internacional,iv internacional\" \/>\n\t<link rel=\"canonical\" href=\"http:\/\/posicuarta.org\/cartasblog\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Carta Semanal | Todas las semanas el POSI publica esta carta sobre temas de actualidad\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00a1Ahora es urgente parar el golpe de los jueces que est\u00e1 en curso! | Carta Semanal\" \/>\n\t\t<meta property=\"og:description\" content=\"Manifiesto del 2\u00ba Encuentro Nacional de Di\u00e1logo y Acci\u00f3n Petista (agrupamiento de militantes del PT impulsado por la secci\u00f3n de la Cuarta O Trabalho)\" \/>\n\t\t<meta property=\"og:url\" content=\"http:\/\/posicuarta.org\/cartasblog\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-03-28T10:18:29+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-03-28T10:18:29+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00a1Ahora es urgente parar el golpe de los jueces que est\u00e1 en curso! | Carta Semanal\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Manifiesto del 2\u00ba Encuentro Nacional de Di\u00e1logo y Acci\u00f3n Petista (agrupamiento de militantes del PT impulsado por la secci\u00f3n de la Cuarta O Trabalho)\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\\\/#article\",\"name\":\"\\u00a1Ahora es urgente parar el golpe de los jueces que est\\u00e1 en curso! | Carta Semanal\",\"headline\":\"\\u00a1Ahora es urgente parar el golpe de los jueces que est\\u00e1 en curso!\",\"author\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#organization\"},\"datePublished\":\"2016-03-28T12:18:29+02:00\",\"dateModified\":\"2016-03-28T12:18:29+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\\\/#webpage\"},\"isPartOf\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\\\/#webpage\"},\"articleSection\":\"Declaraci\\u00f3n, Internacional, IV Internacional, acci\\u00f3n petista, Brasil, CUT, Dilma Rousseff, Eduardo Cunha, Gilmar Mendes, juez Moro, Lula, Partido de los Trabajadores, PMDB, Minientrada\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/category\\\/organizaciones-obreras\\\/#listItem\",\"name\":\"Organizaciones obreras\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/category\\\/organizaciones-obreras\\\/#listItem\",\"position\":2,\"name\":\"Organizaciones obreras\",\"item\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/category\\\/organizaciones-obreras\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/category\\\/organizaciones-obreras\\\/iv-internacional\\\/#listItem\",\"name\":\"IV Internacional\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/category\\\/organizaciones-obreras\\\/iv-internacional\\\/#listItem\",\"position\":3,\"name\":\"IV Internacional\",\"item\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/category\\\/organizaciones-obreras\\\/iv-internacional\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\\\/#listItem\",\"name\":\"\\u00a1Ahora es urgente parar el golpe de los jueces que est\\u00e1 en curso!\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/category\\\/organizaciones-obreras\\\/#listItem\",\"name\":\"Organizaciones obreras\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\\\/#listItem\",\"position\":4,\"name\":\"\\u00a1Ahora es urgente parar el golpe de los jueces que est\\u00e1 en curso!\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/category\\\/organizaciones-obreras\\\/iv-internacional\\\/#listItem\",\"name\":\"IV Internacional\"}}]},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#organization\",\"name\":\"Carta Semanal\",\"description\":\"Todas las semanas el POSI publica esta carta sobre temas de actualidad\",\"url\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/author\\\/admin\\\/#author\",\"url\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5f86a8150e0ed923470fca03ba20c51f6a89fd5b70e7b345283c4b0866a65ab?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\\\/#webpage\",\"url\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\\\/\",\"name\":\"\\u00a1Ahora es urgente parar el golpe de los jueces que est\\u00e1 en curso! | Carta Semanal\",\"description\":\"Manifiesto del 2\\u00ba Encuentro Nacional de Di\\u00e1logo y Acci\\u00f3n Petista (agrupamiento de militantes del PT impulsado por la secci\\u00f3n de la Cuarta O Trabalho)\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\\\/#breadcrumblist\"},\"author\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2016-03-28T12:18:29+02:00\",\"dateModified\":\"2016-03-28T12:18:29+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#website\",\"url\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/\",\"name\":\"Carta Semanal\",\"description\":\"Todas las semanas el POSI publica esta carta sobre temas de actualidad\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u00a1Ahora es urgente parar el golpe de los jueces que est\u00e1 en curso! | Carta Semanal","description":"Manifiesto del 2\u00ba Encuentro Nacional de Di\u00e1logo y Acci\u00f3n Petista (agrupamiento de militantes del PT impulsado por la secci\u00f3n de la Cuarta O Trabalho)","canonical_url":"http:\/\/posicuarta.org\/cartasblog\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\/","robots":"max-image-preview:large","keywords":"acci\u00f3n petista,brasil,cut,dilma rousseff,eduardo cunha,gilmar mendes,juez moro,lula,partido de los trabajadores,pmdb,declaraci\u00f3n,internacional,iv internacional","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/posicuarta.org\/cartasblog\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\/#article","name":"\u00a1Ahora es urgente parar el golpe de los jueces que est\u00e1 en curso! | Carta Semanal","headline":"\u00a1Ahora es urgente parar el golpe de los jueces que est\u00e1 en curso!","author":{"@id":"http:\/\/posicuarta.org\/cartasblog\/author\/admin\/#author"},"publisher":{"@id":"http:\/\/posicuarta.org\/cartasblog\/#organization"},"datePublished":"2016-03-28T12:18:29+02:00","dateModified":"2016-03-28T12:18:29+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"http:\/\/posicuarta.org\/cartasblog\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\/#webpage"},"isPartOf":{"@id":"http:\/\/posicuarta.org\/cartasblog\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\/#webpage"},"articleSection":"Declaraci\u00f3n, Internacional, IV Internacional, acci\u00f3n petista, Brasil, CUT, Dilma Rousseff, Eduardo Cunha, Gilmar Mendes, juez Moro, Lula, Partido de los Trabajadores, PMDB, Minientrada"},{"@type":"BreadcrumbList","@id":"http:\/\/posicuarta.org\/cartasblog\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog#listItem","position":1,"name":"Home","item":"http:\/\/posicuarta.org\/cartasblog","nextItem":{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog\/category\/organizaciones-obreras\/#listItem","name":"Organizaciones obreras"}},{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog\/category\/organizaciones-obreras\/#listItem","position":2,"name":"Organizaciones obreras","item":"http:\/\/posicuarta.org\/cartasblog\/category\/organizaciones-obreras\/","nextItem":{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog\/category\/organizaciones-obreras\/iv-internacional\/#listItem","name":"IV Internacional"},"previousItem":{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog#listItem","name":"Home"}},{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog\/category\/organizaciones-obreras\/iv-internacional\/#listItem","position":3,"name":"IV Internacional","item":"http:\/\/posicuarta.org\/cartasblog\/category\/organizaciones-obreras\/iv-internacional\/","nextItem":{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\/#listItem","name":"\u00a1Ahora es urgente parar el golpe de los jueces que est\u00e1 en curso!"},"previousItem":{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog\/category\/organizaciones-obreras\/#listItem","name":"Organizaciones obreras"}},{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\/#listItem","position":4,"name":"\u00a1Ahora es urgente parar el golpe de los jueces que est\u00e1 en curso!","previousItem":{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog\/category\/organizaciones-obreras\/iv-internacional\/#listItem","name":"IV Internacional"}}]},{"@type":"Organization","@id":"http:\/\/posicuarta.org\/cartasblog\/#organization","name":"Carta Semanal","description":"Todas las semanas el POSI publica esta carta sobre temas de actualidad","url":"http:\/\/posicuarta.org\/cartasblog\/"},{"@type":"Person","@id":"http:\/\/posicuarta.org\/cartasblog\/author\/admin\/#author","url":"http:\/\/posicuarta.org\/cartasblog\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"http:\/\/posicuarta.org\/cartasblog\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/e5f86a8150e0ed923470fca03ba20c51f6a89fd5b70e7b345283c4b0866a65ab?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"http:\/\/posicuarta.org\/cartasblog\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\/#webpage","url":"http:\/\/posicuarta.org\/cartasblog\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\/","name":"\u00a1Ahora es urgente parar el golpe de los jueces que est\u00e1 en curso! | Carta Semanal","description":"Manifiesto del 2\u00ba Encuentro Nacional de Di\u00e1logo y Acci\u00f3n Petista (agrupamiento de militantes del PT impulsado por la secci\u00f3n de la Cuarta O Trabalho)","inLanguage":"es-ES","isPartOf":{"@id":"http:\/\/posicuarta.org\/cartasblog\/#website"},"breadcrumb":{"@id":"http:\/\/posicuarta.org\/cartasblog\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\/#breadcrumblist"},"author":{"@id":"http:\/\/posicuarta.org\/cartasblog\/author\/admin\/#author"},"creator":{"@id":"http:\/\/posicuarta.org\/cartasblog\/author\/admin\/#author"},"datePublished":"2016-03-28T12:18:29+02:00","dateModified":"2016-03-28T12:18:29+02:00"},{"@type":"WebSite","@id":"http:\/\/posicuarta.org\/cartasblog\/#website","url":"http:\/\/posicuarta.org\/cartasblog\/","name":"Carta Semanal","description":"Todas las semanas el POSI publica esta carta sobre temas de actualidad","inLanguage":"es-ES","publisher":{"@id":"http:\/\/posicuarta.org\/cartasblog\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Carta Semanal | Todas las semanas el POSI publica esta carta sobre temas de actualidad","og:type":"article","og:title":"\u00a1Ahora es urgente parar el golpe de los jueces que est\u00e1 en curso! | Carta Semanal","og:description":"Manifiesto del 2\u00ba Encuentro Nacional de Di\u00e1logo y Acci\u00f3n Petista (agrupamiento de militantes del PT impulsado por la secci\u00f3n de la Cuarta O Trabalho)","og:url":"http:\/\/posicuarta.org\/cartasblog\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\/","article:published_time":"2016-03-28T10:18:29+00:00","article:modified_time":"2016-03-28T10:18:29+00:00","twitter:card":"summary","twitter:title":"\u00a1Ahora es urgente parar el golpe de los jueces que est\u00e1 en curso! | Carta Semanal","twitter:description":"Manifiesto del 2\u00ba Encuentro Nacional de Di\u00e1logo y Acci\u00f3n Petista (agrupamiento de militantes del PT impulsado por la secci\u00f3n de la Cuarta O Trabalho)"},"aioseo_meta_data":{"post_id":"2136","title":"\u00a1Ahora es urgente parar el golpe de los jueces que est\u00e1 en curso! | #site_title","description":"Manifiesto del 2\u00ba Encuentro Nacional de Di\u00e1logo y Acci\u00f3n Petista (agrupamiento de militantes del PT impulsado por la secci\u00f3n de la Cuarta O Trabalho)","keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-15 19:15:33","updated":"2025-07-01 13:56:45","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/posicuarta.org\/cartasblog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/posicuarta.org\/cartasblog\/category\/organizaciones-obreras\/\" title=\"Organizaciones obreras\">Organizaciones obreras<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/posicuarta.org\/cartasblog\/category\/organizaciones-obreras\/iv-internacional\/\" title=\"IV Internacional\">IV Internacional<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00a1Ahora es urgente parar el golpe de los jueces que est\u00e1 en curso!\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"http:\/\/posicuarta.org\/cartasblog"},{"label":"Organizaciones obreras","link":"http:\/\/posicuarta.org\/cartasblog\/category\/organizaciones-obreras\/"},{"label":"IV Internacional","link":"http:\/\/posicuarta.org\/cartasblog\/category\/organizaciones-obreras\/iv-internacional\/"},{"label":"\u00a1Ahora es urgente parar el golpe de los jueces que est\u00e1 en curso!","link":"http:\/\/posicuarta.org\/cartasblog\/ahora-es-urgente-parar-el-golpe-de-los-jueces-que-esta-en-curso\/"}],"_links":{"self":[{"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/posts\/2136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/comments?post=2136"}],"version-history":[{"count":2,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/posts\/2136\/revisions"}],"predecessor-version":[{"id":2138,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/posts\/2136\/revisions\/2138"}],"wp:attachment":[{"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/media?parent=2136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/categories?post=2136"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/tags?post=2136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}