{"id":2761,"date":"2017-04-26T12:18:29","date_gmt":"2017-04-26T10:18:29","guid":{"rendered":"http:\/\/posicuarta.org\/cartasblog\/?p=2761"},"modified":"2017-05-29T13:04:50","modified_gmt":"2017-05-29T11:04:50","slug":"presentacion-combate-socialista-mayo-de-1937","status":"publish","type":"post","link":"http:\/\/posicuarta.org\/cartasblog\/presentacion-combate-socialista-mayo-de-1937\/","title":{"rendered":"Presentaci\u00f3n Combate Socialista &#8211; mayo de 1937"},"content":{"rendered":"<h3 style=\"text-align: justify;\">PRESENTACI\u00d3N: \u00abEn el 80 aniversario de la insurrecci\u00f3n obrera de mayo de 1937: Diez meses de revoluci\u00f3n y contrarrevoluci\u00f3n\u00bb<\/h3>\n<p style=\"text-align: justify;\"><strong><em>Autor: Josep Antoni Pozo Gonz\u00e1lez<\/em><br \/>\n<\/strong><\/p>\n<div id=\"attachment_2762\" style=\"width: 160px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/posicuarta.org\/cartasblog\/combate-socialista\/\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2762\" class=\"wp-image-2762\" src=\"http:\/\/posicuarta.org\/cartasblog\/wp-content\/uploads\/2017\/04\/ColeccionCS.jpg\" alt=\"\" width=\"150\" height=\"224\" srcset=\"http:\/\/posicuarta.org\/cartasblog\/wp-content\/uploads\/2017\/04\/ColeccionCS.jpg 419w, http:\/\/posicuarta.org\/cartasblog\/wp-content\/uploads\/2017\/04\/ColeccionCS-100x150.jpg 100w, http:\/\/posicuarta.org\/cartasblog\/wp-content\/uploads\/2017\/04\/ColeccionCS-200x300.jpg 200w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><p id=\"caption-attachment-2762\" class=\"wp-caption-text\">Accede a la p\u00e1gina de Combate Socialista<\/p><\/div>\n<p style=\"text-align: justify;\">Diez meses separan las jornadas de julio de 1936, de las barricadas levantadas en Barcelona durante los primeros d\u00edas del mes de mayo de 1937. Diez meses en los que la revoluci\u00f3n social que estall\u00f3 en respuesta al golpe de Estado de los militares, fue subsistiendo en medio de una guerra civil, sin que los dirigentes de las organizaciones que se reclamaban del movimiento obrero quisieran, unos, o fueran capaces, otros, de conducirla hacia la toma del poder, \u00fanica forma de garantizar el triunfo pleno de aquella.<\/p>\n<p style=\"text-align: justify;\">Durante todo ese per\u00edodo, los obreros y campesinos resistieron con las armas en la mano a los generales facciosos, se apoderaron de f\u00e1bricas y tierras, establecieron el control obrero en la industria y los servicios, y levantaron organismos de poder revolucionario que substituyeron localmente a las autoridades legales. Y lo hicieron casi intuitivamente. Con el convencimiento de que era la mejor manera de combatir al fascismo. Porque, efectivamente, la mejor estrategia para vencerlo militarmente no era otra que la de desplegar consecuentemente el programa revolucionario de emancipaci\u00f3n social. No hab\u00eda arma m\u00e1s poderosa que \u00e9sta.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-2765\" src=\"http:\/\/posicuarta.org\/cartasblog\/wp-content\/uploads\/2017\/04\/arton38349.jpg\" alt=\"\" width=\"640\" height=\"422\" srcset=\"http:\/\/posicuarta.org\/cartasblog\/wp-content\/uploads\/2017\/04\/arton38349.jpg 640w, http:\/\/posicuarta.org\/cartasblog\/wp-content\/uploads\/2017\/04\/arton38349-150x99.jpg 150w, http:\/\/posicuarta.org\/cartasblog\/wp-content\/uploads\/2017\/04\/arton38349-300x198.jpg 300w, http:\/\/posicuarta.org\/cartasblog\/wp-content\/uploads\/2017\/04\/arton38349-624x411.jpg 624w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>Pero durante todo este per\u00edodo, los dirigentes de las principales organizaciones del movimiento obrero hicieron todo lo posible por \u201cencauzar\u201d la revoluci\u00f3n, por impedir que traspasara los l\u00edmites del Estado burgu\u00e9s, y cedieron ante las propias exigencias de los gobiernos imperialistas europeos que con su pol\u00edtica de No-Intervenci\u00f3n, contribuyeron a aislar a los trabajadores espa\u00f1oles. Unos, como por ejemplo Indalecio Prieto y el ala derechista del PSOE, porque consideraban que Espa\u00f1a no estaba madura para una revoluci\u00f3n de tipo socialista. En esto coincid\u00edan con los dirigentes del PCE-PSUC, y con el mismo Stalin, qui\u00e9n en carta al entonces presidente del gobierno de la Rep\u00fablica, Largo Caballero, le \u201caconsejaba\u201d sobre la conveniencia de respetar la propiedad privada y la necesidad de no aplicar medidas revolucionarias. Y otros, como los dirigentes de la CNT y la FAI, y tambi\u00e9n del POUM, por su incapacidad para organizar la revoluci\u00f3n de la que se reclamaban, y a la que no ayudaron en absoluto participando en los gobiernos que se propusieron como objetivo pol\u00edtico prioritario acabar con ella.<\/p>\n<p style=\"text-align: justify;\">El sector caballerista tuvo igualmente mucha responsabilidad en ese sentido. Despu\u00e9s de que durante el mes de agosto hubiera explorado \u2013y desechado- la posibilidad de constituir un \u201cgobierno obrero\u201d formado por la UGT y la CNT, se avino finalmente a substituir al gobierno Giral por otro de concentraci\u00f3n de fuerzas de tipo frentepopulista. As\u00ed, en septiembre de 1936 se constituy\u00f3 en Madrid un gobierno presidido por el secretario general de la UGT, Largo Caballero, con la participaci\u00f3n de seis ministros socialistas \u2013en representaci\u00f3n del PSOE y de la UGT-, tres procedentes de los partidos republicanos burgueses \u2013IR y UR-, dos ministros del PCE, y dos ministros que representaban ERC y PNV respectivamente. Como explic\u00f3 Largo Caballero a Koltsov pocos d\u00edas despu\u00e9s, lo que acababan de constituir era un \u201cun organismo \u00fanico, con un objetivo \u00fanico: derrotar al fascismo\u201d. Era lo que quer\u00edan o\u00edr tanto Stalin como los gobiernos \u201cdemocr\u00e1ticos\u201d de Francia e Inglaterra.<\/p>\n<p style=\"text-align: justify;\">La CNT no particip\u00f3 inicialmente en este gobierno pero si lo har\u00eda en el que se constituy\u00f3 en noviembre, presidido tambi\u00e9n por Largo caballero, despu\u00e9s de que los cenetistas catalanes decidieron integrarse, en ese mismo mes de septiembre, en el gobierno de la Generalidad de \u201cunidad antifascista\u201d. Gobierno del que tambi\u00e9n form\u00f3 parte el POUM hasta su expulsi\u00f3n del mismo, y cuya primera medida fue precisamente disolver todos los comit\u00e9s revolucionarios que exist\u00edan en Catalunya.<\/p>\n<p style=\"text-align: justify;\">Con la ayuda de estos gobiernos, poco a poco, fue restableci\u00e9ndose la legalidad republicana en contraposici\u00f3n a las conquistas revolucionarias. En el campo obrero, uno de los argumentos para convencer a los militantes que se resist\u00edan, fue que hab\u00eda que sacrificar todo, incluido la revoluci\u00f3n, al objetivo com\u00fan y prioritario de ganar primero la guerra. Un argumento que se demostrar\u00eda tr\u00e1gicamente falaz, y detr\u00e1s del cual se parapetaron todos los que, en el campo republicano y entre los gobiernos europeos supuestamente interesados en parar los pies al fascismo, no quer\u00edan de ninguna manera que hubiera una revoluci\u00f3n socialista triunfante en Espa\u00f1a. Desde los Stalin, Blum y Chamberlain, hasta el propio Aza\u00f1a, pasando por Companys e Irujo.<\/p>\n<p style=\"text-align: justify;\">Sin embargo, el objetivo de restaurar la legalidad republicana contra las conquistas revolucionarias, choc\u00f3 con la resistencia de la clase obrera, especialmente en Catalunya, dando lugar a una situaci\u00f3n de conflictividad extrema. Durante el \u00faltimo trimestre de 1936 y los primeros meses de 1937, tuvo lugar en la retaguardia catalana una lucha enconada entre los partidarios de implantar cuanto antes un orden \u201cantifascista\u201d \u2013el gobierno de la Generalidad y los dirigentes de las organizaciones que lo apoyaban incondicionalmente, el PSUC, ERC, UR, y ACR-, y quienes se aferraban al esp\u00edritu del \u201c19 de julio\u201d, es decir, a la defensa de un orden revolucionario, de las colectivizaciones, de las patrullas de control, etc., integrados aunque no exclusivamente, en el movimiento libertario y el POUM.<\/p>\n<p style=\"text-align: justify;\">Y fue precisamente en Catalunya, donde subsist\u00eda buena parte de las conquistas revolucionarias, donde centraron su atenci\u00f3n quienes ten\u00edan el objetivo de acabar con cualquier atisbo de oposici\u00f3n. Durante la primavera de 1937, los conflictos derivados de las denuncias de antiguos propietarios que hab\u00edan sido expropiados en los meses anteriores, o los enfrentamientos entre miembros de las patrullas de control y los cuerpos de polic\u00eda \u201coficiales\u201d, se incrementaron notablemente. Desde diciembre de 1936, hab\u00eda sido nombrado un nuevo Comisario de Orden P\u00fablico, Eusebio Rodr\u00edguez Salas, un militante del PSUC, quien declar\u00f3 en el momento de tomar posesi\u00f3n de su cargo, su disposici\u00f3n a hacer cumplir lo que el Gobierno acordara y a actuar con firmeza para acabar con los \u201cincontrolados\u201d. Eufemismo con el que se hac\u00eda referencia a todos aquellos militantes que se resist\u00edan a aceptar las disposiciones del gobierno que liquidaban las conquistas revolucionarias, y pretend\u00edan anular la correlaci\u00f3n de fuerzas establecida durante las jornadas de julio a nivel local por los comit\u00e9s revolucionarios.<\/p>\n<p style=\"text-align: justify;\">Era toda una declaraci\u00f3n de intenciones y, por otro lado, la se\u00f1al que esperaban los partidarios de acabar con los \u201cexcesos\u201d revolucionarios. Despu\u00e9s de los hechos acaecidos en diversas poblaciones catalanas \u2013La Garriga, La Fatarella, etc.- la actitud provocadora de la polic\u00eda fue en aumento. Y la determinaci\u00f3n del gobierno de la Generalidad tambi\u00e9n. Amparados en la presencia de representantes cenetistas en el gobierno, el 12 de febrero el Consejero de Seguridad Interior y militante de ERC, Artemi Aiguader, presenta un plan de reorganizaci\u00f3n de los servicios policiales que incluye la disoluci\u00f3n de las patrullas de control y de los consejos de obreros y soldados que operaban en los distintos cuerpos policiales, la prohibici\u00f3n para los Ayuntamientos de mantener las funciones de Seguridad y Defensa en los casos en los que todav\u00eda se ejercieran, as\u00ed como el restablecimiento de la censura. El 20 de este mismo mes, el gobierno de la Generalidad declaraba nulas todas las colectivizaciones que no se hubieran realizado de acuerdo con el decreto que las regulaba, y el 27 se organiza en Barcelona una manifestaci\u00f3n de polic\u00edas que ped\u00edan la dimisi\u00f3n del Jefe Superior, el cenetista Eroles.<\/p>\n<p style=\"text-align: justify;\">En pleno \u201coleaje contrarevolucionario\u201d como calificaba la situaci\u00f3n uno de los futuros impulsores de la Agrupaci\u00f3n <em>Los Amigos de Durruti<\/em>, Jaime Balius, el \u00f3rgano del POUM recibe el 12 de marzo una orden de suspensi\u00f3n que es anulada horas despu\u00e9s. El art\u00edculo que provoc\u00f3 la orden de suspensi\u00f3n llevaba por t\u00edtulo \u201c\u00bfSe intenta entregar Madrid al fascismo para negociar un abrazo de Vergara?\u201d. Con anterioridad, <em>La Batalla <\/em>ya hab\u00eda recibido una sanci\u00f3n de 5000 pesetas. El 18 de marzo, unos guardias intentan asaltar el local del Sindicato de la Metalurgia de la CNT. Por otra parte, el gobierno de la Generalidad entra en crisis, despu\u00e9s de mostrarse impotente para hacer cumplir los decretos sobre reorganizaci\u00f3n de los servicios policiales que fueron aprobados finalmente el 1 de marzo.<\/p>\n<p style=\"text-align: justify;\">Durante el mes de abril los acontecimientos se precipitan. Rold\u00e1n Cortada, militante del PSUC y dirigente de la UGT es asesinado en un control de carreteras. La prensa del PSUC acusa inmediatamente de su muerte a los anarquistas de l\u2019Hospitalet, quienes a su vez ten\u00edan la informaci\u00f3n que Cortada hab\u00eda ido a Par\u00eds a comprar armas cortas para dar la batalla a la FAI. Dos d\u00edas m\u00e1s tarde se producen los enfrentamientos en un peque\u00f1o pueblo, Bellver de Cerdanya, muy cerca de la frontera con Francia, donde encuentra la muerte el dirigente anarquista de Puigcerd\u00e0 Antonio Mart\u00edn.<\/p>\n<p style=\"text-align: justify;\">La situaci\u00f3n es cr\u00edtica y no faltan voces, dentro y fuera del gobierno, que exigen actuar de inmediato contra los anarquistas y la \u201cchusma revolucionaria\u201d. Los actos del 1 de mayo son anulados por temor a que se produzca alg\u00fan incidente, pero tambi\u00e9n por temor a que puedan ser escenario de alguna demostraci\u00f3n de protesta entre los sindicatos cenetistas, las Juventudes Libertarias y el POUM.<\/p>\n<p style=\"text-align: justify;\">Los hechos que se suceden a continuaci\u00f3n son m\u00e1s o menos conocidos. El lunes 3 de mayo, dos camionetas de Guardias de Asalto, dirigidos por Rodr\u00edguez Salas, asaltan el edificio de la Telef\u00f3nica con la pretensi\u00f3n de recuperar los servicios que se encuentran desde julio, bajo control de un comit\u00e9 obrero CNT-UGT. La noticia se extiende por toda Barcelona, e inmediatamente se produce una reacci\u00f3n espont\u00e1nea de buena parte del proletariado de la ciudad, que levanta barricadas en el centro y en las barriadas. Inicialmente, los obreros que se lanzan a la calle creen que se trata de una provocaci\u00f3n policial, una m\u00e1s de las muchas que se hab\u00edan producido en las semanas anteriores. Por la noche, se produce una reuni\u00f3n de urgencia del gobierno catal\u00e1n. Los representantes de la CNT exigen la dimisi\u00f3n de Aiguader y de Rodr\u00edguez Salas, pero Companys no solo se niega a ello sino que los defiende. Es entonces cuando la militancia que se ha echado a la calle comprende que se trata de algo mucho m\u00e1s grave y muchas f\u00e1bricas se declaran en huelga, mientras que los transportes paran. El d\u00eda 4, la insurrecci\u00f3n es un hecho. Los obreros se han apoderado de la ciudad y el movimiento se extiende a otras localidades catalanas, pero los dirigentes de la CNT vacilan y claudican finalmente, mientras que los del POUM \u2013que en los primeros instantes de la insurrecci\u00f3n hab\u00edan declarado que hab\u00eda llegado el momento de aplastar la contrarevoluci\u00f3n- se acaban adaptando y ceden.<\/p>\n<p style=\"text-align: justify;\">Lo que sigui\u00f3 tambi\u00e9n es conocido. La represi\u00f3n contra los militantes revolucionarios se desat\u00f3 inmediatamente. La campa\u00f1a estalinista se puso en marcha y apunt\u00f3 directamente al POUM como instigador del \u201cputsch\u201d, es decir, como si fueran los ejecutores de un plan premeditado que solo exist\u00eda en la imaginaci\u00f3n de quienes cultivaron esa versi\u00f3n para justificar las calumnias y los asesinatos. El 8 de mayo, el secretario general de la UGT de Catalunya, Jos\u00e9 del Barrio, enviaba una circular a todos los sindicatos comunicando la expulsi\u00f3n de los dirigentes del POUM y exhort\u00e1ndolos a que fueran igualmente expulsados todos los militantes de este partido que no condenaran los hechos. El 13, en una reuni\u00f3n del gobierno de la Rep\u00fablica, los ministros del PCE piden la ilegalizaci\u00f3n del POUM, a lo que se niega Largo Caballero. Los ministros del PCE abandonan la reuni\u00f3n en se\u00f1al de protesta, provocando la crisis y la dimisi\u00f3n posterior de Largo Caballero que ser\u00eda substituido por Negr\u00edn. El 28 de mayo el \u00f3rgano del POUM, <em>La Batalla<\/em>, es prohibido y los talleres donde se edita incautados.<\/p>\n<p style=\"text-align: justify;\">El 4 de junio son disueltas oficialmente las Patrullas de Control, y el 16 es detenido Nin y todo el Comit\u00e9 Ejecutivo del POUM. Nin es conducido a una prisi\u00f3n privada y asesinado por orden de Stalin. Otros militantes correr\u00edan su misma suerte. Centenares ser\u00edan detenidos y encarcelados, entre los cuales, muchos militantes cenetistas.<\/p>\n<p style=\"text-align: justify;\">La insurrecci\u00f3n obrera de mayo de 1937 fue el \u00faltimo episodio de la revoluci\u00f3n espa\u00f1ola. La \u00faltima posibilidad de corregir el curso contrarevolucionario y dar un giro a la situaci\u00f3n y al desarrollo de la guerra. La derrota de los obreros barceloneses constituy\u00f3 un golpe mortal para la suerte de la revoluci\u00f3n y, como pudo comprobarse posteriormente, tambi\u00e9n para el desenlace de la guerra. Naturalmente, la llama de la revoluci\u00f3n no se apag\u00f3 inmediatamente. De hecho continu\u00f3 encendida aunque t\u00edmidamente, a trav\u00e9s por ejemplo del combate de muchos militantes y sindicatos cenetistas, por la liberaci\u00f3n de los presos antifascistas que poblaban las c\u00e1rceles y que fueron abandonados a su suerte por la direcci\u00f3n confederal.<\/p>\n<p style=\"text-align: justify;\">En el verano de 1937, un a\u00f1o despu\u00e9s del inicio de la revoluci\u00f3n y la guerra, la Rep\u00fablica espa\u00f1ola estaba m\u00e1s aislada que nunca. A pesar del aplastamiento de la oposici\u00f3n revolucionaria, los gobiernos a los que se encomendaron los dirigentes republicanos espa\u00f1oles no movieron ni un solo dedo para impedir el triunfo de Franco. De hecho, tras la ca\u00edda de Catalu\u00f1a, los gobiernos de Francia e Inglaterra se apresuraron a reconocer al gobierno de Burgos. Stalin por su parte, despu\u00e9s de ajustar cuentas con todos aquellos responsables \u2013diplom\u00e1ticos, asesores militares &#8230;- que tuvieron algo que ver con la revoluci\u00f3n espa\u00f1ola, acabar\u00eda propiciando un pacto de no agresi\u00f3n con la Alemania de Hitler en agosto de 1939.<\/p>\n<p style=\"text-align: justify;\">A prop\u00f3sito de lo ocurrido en Barcelona los primeros d\u00edas de mayo de 1937, y polemizando contra un camarada belga que defend\u00eda que, en lo substancial, el POUM hab\u00eda actuado correctamente, y que intentar tomar el poder en aquellas circunstancias era puro aventurismo, Le\u00f3n Trotsky afirmaba por el contrario, que esta posibilidad no solo estuvo al alcance de la mano, sino que adem\u00e1s, si se hubiera producido habr\u00eda sido coronada muy probablemente por el \u00e9xito. Naturalmente, escrib\u00eda Trotsky, \u201cen toda insurrecci\u00f3n hay un elemento inesperado y de riesgo. Pero toda la marcha ulterior de los acontecimientos ha demostrado que, incluso en caso de derrota, la situaci\u00f3n del proletariado espa\u00f1ol hubiera sido incomparablemente m\u00e1s favorable que lo es ahora, sin tener necesidad de decir que el partido revolucionario hubiera asegurado su porvenir para siempre\u201d. (<em>La verificaci\u00f3n de las ideas y de los individuos a trav\u00e9s de la revoluci\u00f3n espa\u00f1ola<\/em>, 24 agosto 1937. Texto dirigido a todas las secciones de la IV Internacional).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PRESENTACI\u00d3N: \u00abEn el 80 aniversario de la insurrecci\u00f3n obrera de mayo de 1937: Diez meses de revoluci\u00f3n y contrarrevoluci\u00f3n\u00bb Autor: Josep Antoni Pozo Gonz\u00e1lez Diez meses separan las jornadas de julio de 1936, de las barricadas levantadas en Barcelona durante los primeros d\u00edas del mes de mayo de 1937. Diez meses en los que la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[292],"tags":[822,824,215,232,821,823,99],"class_list":["post-2761","post","type-post","status-publish","format-standard","hentry","category-combate-socialista","tag-19-de-julio-de-1936","tag-amigos-de-durruti","tag-barcelona","tag-cnt","tag-mayo-1937","tag-pce-psuc","tag-poum"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"PRESENTACI\u00d3N: &quot;En el 80 aniversario de la insurrecci\u00f3n obrera de mayo de 1937: Diez meses de revoluci\u00f3n y contrarrevoluci\u00f3n&quot; Autor: Josep Antoni Pozo Gonz\u00e1lez Diez meses separan las jornadas de julio de 1936, de las barricadas levantadas en Barcelona durante los primeros d\u00edas del mes de mayo de 1937. Diez meses en los que la\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"keywords\" content=\"19 de julio de 1936,amigos de durruti,barcelona,cnt,mayo 1937,pce-psuc,poum,combate socialista\" \/>\n\t<link rel=\"canonical\" href=\"http:\/\/posicuarta.org\/cartasblog\/presentacion-combate-socialista-mayo-de-1937\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Carta Semanal | Todas las semanas el POSI publica esta carta sobre temas de actualidad\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Presentaci\u00f3n Combate Socialista \u2013 mayo de 1937 | Carta Semanal\" \/>\n\t\t<meta property=\"og:description\" content=\"PRESENTACI\u00d3N: &quot;En el 80 aniversario de la insurrecci\u00f3n obrera de mayo de 1937: Diez meses de revoluci\u00f3n y contrarrevoluci\u00f3n&quot; Autor: Josep Antoni Pozo Gonz\u00e1lez Diez meses separan las jornadas de julio de 1936, de las barricadas levantadas en Barcelona durante los primeros d\u00edas del mes de mayo de 1937. Diez meses en los que la\" \/>\n\t\t<meta property=\"og:url\" content=\"http:\/\/posicuarta.org\/cartasblog\/presentacion-combate-socialista-mayo-de-1937\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-04-26T10:18:29+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-05-29T11:04:50+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Presentaci\u00f3n Combate Socialista \u2013 mayo de 1937 | Carta Semanal\" \/>\n\t\t<meta name=\"twitter:description\" content=\"PRESENTACI\u00d3N: &quot;En el 80 aniversario de la insurrecci\u00f3n obrera de mayo de 1937: Diez meses de revoluci\u00f3n y contrarrevoluci\u00f3n&quot; Autor: Josep Antoni Pozo Gonz\u00e1lez Diez meses separan las jornadas de julio de 1936, de las barricadas levantadas en Barcelona durante los primeros d\u00edas del mes de mayo de 1937. Diez meses en los que la\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/presentacion-combate-socialista-mayo-de-1937\\\/#article\",\"name\":\"Presentaci\\u00f3n Combate Socialista \\u2013 mayo de 1937 | Carta Semanal\",\"headline\":\"Presentaci\\u00f3n Combate Socialista &#8211; mayo de 1937\",\"author\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/ColeccionCS.jpg\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/presentacion-combate-socialista-mayo-de-1937\\\/#articleImage\",\"width\":419,\"height\":627},\"datePublished\":\"2017-04-26T12:18:29+02:00\",\"dateModified\":\"2017-05-29T13:04:50+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/presentacion-combate-socialista-mayo-de-1937\\\/#webpage\"},\"isPartOf\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/presentacion-combate-socialista-mayo-de-1937\\\/#webpage\"},\"articleSection\":\"Combate Socialista, 19 de julio de 1936, Amigos de Durruti, Barcelona, cnt, mayo 1937, PCE-PSUC, POUM\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/presentacion-combate-socialista-mayo-de-1937\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/category\\\/combate-socialista\\\/#listItem\",\"name\":\"Combate Socialista\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/category\\\/combate-socialista\\\/#listItem\",\"position\":2,\"name\":\"Combate Socialista\",\"item\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/category\\\/combate-socialista\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/presentacion-combate-socialista-mayo-de-1937\\\/#listItem\",\"name\":\"Presentaci\\u00f3n Combate Socialista &#8211; mayo de 1937\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/presentacion-combate-socialista-mayo-de-1937\\\/#listItem\",\"position\":3,\"name\":\"Presentaci\\u00f3n Combate Socialista &#8211; mayo de 1937\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/category\\\/combate-socialista\\\/#listItem\",\"name\":\"Combate Socialista\"}}]},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#organization\",\"name\":\"Carta Semanal\",\"description\":\"Todas las semanas el POSI publica esta carta sobre temas de actualidad\",\"url\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/author\\\/admin\\\/#author\",\"url\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/presentacion-combate-socialista-mayo-de-1937\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5f86a8150e0ed923470fca03ba20c51f6a89fd5b70e7b345283c4b0866a65ab?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/presentacion-combate-socialista-mayo-de-1937\\\/#webpage\",\"url\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/presentacion-combate-socialista-mayo-de-1937\\\/\",\"name\":\"Presentaci\\u00f3n Combate Socialista \\u2013 mayo de 1937 | Carta Semanal\",\"description\":\"PRESENTACI\\u00d3N: \\\"En el 80 aniversario de la insurrecci\\u00f3n obrera de mayo de 1937: Diez meses de revoluci\\u00f3n y contrarrevoluci\\u00f3n\\\" Autor: Josep Antoni Pozo Gonz\\u00e1lez Diez meses separan las jornadas de julio de 1936, de las barricadas levantadas en Barcelona durante los primeros d\\u00edas del mes de mayo de 1937. Diez meses en los que la\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/presentacion-combate-socialista-mayo-de-1937\\\/#breadcrumblist\"},\"author\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2017-04-26T12:18:29+02:00\",\"dateModified\":\"2017-05-29T13:04:50+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#website\",\"url\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/\",\"name\":\"Carta Semanal\",\"description\":\"Todas las semanas el POSI publica esta carta sobre temas de actualidad\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Presentaci\u00f3n Combate Socialista \u2013 mayo de 1937 | Carta Semanal","description":"PRESENTACI\u00d3N: \"En el 80 aniversario de la insurrecci\u00f3n obrera de mayo de 1937: Diez meses de revoluci\u00f3n y contrarrevoluci\u00f3n\" Autor: Josep Antoni Pozo Gonz\u00e1lez Diez meses separan las jornadas de julio de 1936, de las barricadas levantadas en Barcelona durante los primeros d\u00edas del mes de mayo de 1937. Diez meses en los que la","canonical_url":"http:\/\/posicuarta.org\/cartasblog\/presentacion-combate-socialista-mayo-de-1937\/","robots":"max-image-preview:large","keywords":"19 de julio de 1936,amigos de durruti,barcelona,cnt,mayo 1937,pce-psuc,poum,combate socialista","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/posicuarta.org\/cartasblog\/presentacion-combate-socialista-mayo-de-1937\/#article","name":"Presentaci\u00f3n Combate Socialista \u2013 mayo de 1937 | Carta Semanal","headline":"Presentaci\u00f3n Combate Socialista &#8211; mayo de 1937","author":{"@id":"http:\/\/posicuarta.org\/cartasblog\/author\/admin\/#author"},"publisher":{"@id":"http:\/\/posicuarta.org\/cartasblog\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/posicuarta.org\/cartasblog\/wp-content\/uploads\/2017\/04\/ColeccionCS.jpg","@id":"http:\/\/posicuarta.org\/cartasblog\/presentacion-combate-socialista-mayo-de-1937\/#articleImage","width":419,"height":627},"datePublished":"2017-04-26T12:18:29+02:00","dateModified":"2017-05-29T13:04:50+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"http:\/\/posicuarta.org\/cartasblog\/presentacion-combate-socialista-mayo-de-1937\/#webpage"},"isPartOf":{"@id":"http:\/\/posicuarta.org\/cartasblog\/presentacion-combate-socialista-mayo-de-1937\/#webpage"},"articleSection":"Combate Socialista, 19 de julio de 1936, Amigos de Durruti, Barcelona, cnt, mayo 1937, PCE-PSUC, POUM"},{"@type":"BreadcrumbList","@id":"http:\/\/posicuarta.org\/cartasblog\/presentacion-combate-socialista-mayo-de-1937\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog#listItem","position":1,"name":"Home","item":"http:\/\/posicuarta.org\/cartasblog","nextItem":{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog\/category\/combate-socialista\/#listItem","name":"Combate Socialista"}},{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog\/category\/combate-socialista\/#listItem","position":2,"name":"Combate Socialista","item":"http:\/\/posicuarta.org\/cartasblog\/category\/combate-socialista\/","nextItem":{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog\/presentacion-combate-socialista-mayo-de-1937\/#listItem","name":"Presentaci\u00f3n Combate Socialista &#8211; mayo de 1937"},"previousItem":{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog#listItem","name":"Home"}},{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog\/presentacion-combate-socialista-mayo-de-1937\/#listItem","position":3,"name":"Presentaci\u00f3n Combate Socialista &#8211; mayo de 1937","previousItem":{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog\/category\/combate-socialista\/#listItem","name":"Combate Socialista"}}]},{"@type":"Organization","@id":"http:\/\/posicuarta.org\/cartasblog\/#organization","name":"Carta Semanal","description":"Todas las semanas el POSI publica esta carta sobre temas de actualidad","url":"http:\/\/posicuarta.org\/cartasblog\/"},{"@type":"Person","@id":"http:\/\/posicuarta.org\/cartasblog\/author\/admin\/#author","url":"http:\/\/posicuarta.org\/cartasblog\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"http:\/\/posicuarta.org\/cartasblog\/presentacion-combate-socialista-mayo-de-1937\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/e5f86a8150e0ed923470fca03ba20c51f6a89fd5b70e7b345283c4b0866a65ab?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"http:\/\/posicuarta.org\/cartasblog\/presentacion-combate-socialista-mayo-de-1937\/#webpage","url":"http:\/\/posicuarta.org\/cartasblog\/presentacion-combate-socialista-mayo-de-1937\/","name":"Presentaci\u00f3n Combate Socialista \u2013 mayo de 1937 | Carta Semanal","description":"PRESENTACI\u00d3N: \"En el 80 aniversario de la insurrecci\u00f3n obrera de mayo de 1937: Diez meses de revoluci\u00f3n y contrarrevoluci\u00f3n\" Autor: Josep Antoni Pozo Gonz\u00e1lez Diez meses separan las jornadas de julio de 1936, de las barricadas levantadas en Barcelona durante los primeros d\u00edas del mes de mayo de 1937. Diez meses en los que la","inLanguage":"es-ES","isPartOf":{"@id":"http:\/\/posicuarta.org\/cartasblog\/#website"},"breadcrumb":{"@id":"http:\/\/posicuarta.org\/cartasblog\/presentacion-combate-socialista-mayo-de-1937\/#breadcrumblist"},"author":{"@id":"http:\/\/posicuarta.org\/cartasblog\/author\/admin\/#author"},"creator":{"@id":"http:\/\/posicuarta.org\/cartasblog\/author\/admin\/#author"},"datePublished":"2017-04-26T12:18:29+02:00","dateModified":"2017-05-29T13:04:50+02:00"},{"@type":"WebSite","@id":"http:\/\/posicuarta.org\/cartasblog\/#website","url":"http:\/\/posicuarta.org\/cartasblog\/","name":"Carta Semanal","description":"Todas las semanas el POSI publica esta carta sobre temas de actualidad","inLanguage":"es-ES","publisher":{"@id":"http:\/\/posicuarta.org\/cartasblog\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Carta Semanal | Todas las semanas el POSI publica esta carta sobre temas de actualidad","og:type":"article","og:title":"Presentaci\u00f3n Combate Socialista \u2013 mayo de 1937 | Carta Semanal","og:description":"PRESENTACI\u00d3N: &quot;En el 80 aniversario de la insurrecci\u00f3n obrera de mayo de 1937: Diez meses de revoluci\u00f3n y contrarrevoluci\u00f3n&quot; Autor: Josep Antoni Pozo Gonz\u00e1lez Diez meses separan las jornadas de julio de 1936, de las barricadas levantadas en Barcelona durante los primeros d\u00edas del mes de mayo de 1937. Diez meses en los que la","og:url":"http:\/\/posicuarta.org\/cartasblog\/presentacion-combate-socialista-mayo-de-1937\/","article:published_time":"2017-04-26T10:18:29+00:00","article:modified_time":"2017-05-29T11:04:50+00:00","twitter:card":"summary","twitter:title":"Presentaci\u00f3n Combate Socialista \u2013 mayo de 1937 | Carta Semanal","twitter:description":"PRESENTACI\u00d3N: &quot;En el 80 aniversario de la insurrecci\u00f3n obrera de mayo de 1937: Diez meses de revoluci\u00f3n y contrarrevoluci\u00f3n&quot; Autor: Josep Antoni Pozo Gonz\u00e1lez Diez meses separan las jornadas de julio de 1936, de las barricadas levantadas en Barcelona durante los primeros d\u00edas del mes de mayo de 1937. Diez meses en los que la"},"aioseo_meta_data":{"post_id":"2761","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-15 19:16:39","updated":"2025-07-01 14:09:03","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/posicuarta.org\/cartasblog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/posicuarta.org\/cartasblog\/category\/combate-socialista\/\" title=\"Combate Socialista\">Combate Socialista<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPresentaci\u00f3n Combate Socialista \u2013 mayo de 1937\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"http:\/\/posicuarta.org\/cartasblog"},{"label":"Combate Socialista","link":"http:\/\/posicuarta.org\/cartasblog\/category\/combate-socialista\/"},{"label":"Presentaci\u00f3n Combate Socialista &#8211; mayo de 1937","link":"http:\/\/posicuarta.org\/cartasblog\/presentacion-combate-socialista-mayo-de-1937\/"}],"_links":{"self":[{"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/posts\/2761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/comments?post=2761"}],"version-history":[{"count":3,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/posts\/2761\/revisions"}],"predecessor-version":[{"id":2766,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/posts\/2761\/revisions\/2766"}],"wp:attachment":[{"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/media?parent=2761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/categories?post=2761"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/tags?post=2761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}