{"id":2837,"date":"2017-07-17T12:16:46","date_gmt":"2017-07-17T10:16:46","guid":{"rendered":"http:\/\/posicuarta.org\/cartasblog\/?p=2837"},"modified":"2017-07-17T12:16:46","modified_gmt":"2017-07-17T10:16:46","slug":"pensiones-en-defensa-del-actual-sistema-de-reparto","status":"publish","type":"post","link":"http:\/\/posicuarta.org\/cartasblog\/pensiones-en-defensa-del-actual-sistema-de-reparto\/","title":{"rendered":"Pensiones: en defensa del actual sistema de reparto"},"content":{"rendered":"<p><strong>\u00a0<\/strong><em>(Publicado en la <a href=\"http:\/\/www.posicuarta.org\/pdf\/Carta636.pdf\" target=\"_blank\" rel=\"noopener\">Carta Semanal 636<\/a>)<\/em><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/posicuarta.org\/cartasblog\/wp-content\/uploads\/2017\/07\/Carta-636.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-2841\" src=\"http:\/\/posicuarta.org\/cartasblog\/wp-content\/uploads\/2017\/07\/Carta-636.jpg\" alt=\"\" width=\"150\" height=\"215\" srcset=\"http:\/\/posicuarta.org\/cartasblog\/wp-content\/uploads\/2017\/07\/Carta-636.jpg 419w, http:\/\/posicuarta.org\/cartasblog\/wp-content\/uploads\/2017\/07\/Carta-636-105x150.jpg 105w, http:\/\/posicuarta.org\/cartasblog\/wp-content\/uploads\/2017\/07\/Carta-636-210x300.jpg 210w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>La comisi\u00f3n del Pacto de Toledo ten\u00eda previsto resolver con prontitud las propuestas de reformas del actual sistema de pensiones. Las necesidades derivadas de la debilidad del gobierno minoritario de Rajoy exig\u00edan cerrar lo antes posible la discusi\u00f3n sobre las pensiones. Por ello suenan las alarmas cuando se hace patente el alargamiento de los plazos hasta despu\u00e9s del verano. <em>El Pa\u00eds<\/em> del domingo 2 de julio denuncia <strong><em>\u00abnegligencia en las pensiones\u00bb,<\/em><\/strong> urge a cerrar el plan de reformas y califica de <em>\u00ab<strong>irresponsable\u00bb<\/strong><\/em> el acuerdo de aplazar la toma de decisiones. Temen que tome cuerpo en los sindicatos y dem\u00e1s organizaciones obreras el movimiento de rechazo que anida en los colectivos, coordinadoras y agrupamientos creados en defensa del sistema de pensiones con un gobierno en minor\u00eda y responsable, entre otros, de la pol\u00edtica de saqueo y destrucci\u00f3n de la Seguridad Social.<\/p>\n<p><!--more--><\/p>\n<h4>El programa de asistencializaci\u00f3n de la Seguridad Social est\u00e1 en marcha<\/h4>\n<p style=\"text-align: justify;\">Los llamamientos urgentes a proponer medidas para \u00absalvar el futuro de las pensiones\u00bb pretenden esconder una realidad m\u00e1s cercana, como es la actuaci\u00f3n lenta y silenciosa del plan dise\u00f1ado por la reforma de Zapatero de 2011 profundizada por la reforma de Rajoy en 2013. Con estas reformas se dise\u00f1\u00f3 la destrucci\u00f3n del sistema de pensiones tal como la conocemos, y que, de no detenerlo, lo convertir\u00e1 en un sistema de prestaciones cercanas a las asistenciales. El resultado ser\u00eda una p\u00e9rdida del poder adquisitivo cercana al 50% y la ampliaci\u00f3n, poco a poco, del mercado de los fondos privados de pensiones, objetivo constante e irrenunciable del capital financiero.<\/p>\n<p style=\"text-align: justify;\">Su objetivo es abordar la sostenibilidad del sistema de reparto reduciendo los gastos, adapt\u00e1ndolos a los ingresos menguantes propiciados por las reformas laborales, el paro y la eventual reducci\u00f3n de cotizaciones reclamadas por la CEOE. La \u00fanica medida adoptada sobre los ingresos ha consistido en la concesi\u00f3n de pr\u00e9stamos a la Seguridad Social desde el Presupuesto del Estado, que son, por cierto, muy \u00fatiles para simular el cumplimiento de los compromisos del Gobierno con Bruselas trasladando a la Seguridad Social parte del d\u00e9ficit de Estado y para alimentar la falsa opini\u00f3n de que no hay dinero para pagar las pensiones.<\/p>\n<p style=\"text-align: justify;\">Por ello, la primera tarea es organizar la lucha por la derogaci\u00f3n de esas dos reformas, de 2011 y 3013, que, no hay que olvidar, ponen en marcha unos dispositivos autom\u00e1ticos de desvalorizaci\u00f3n de la pensi\u00f3n que chocan con los derechos a pensi\u00f3n de los trabajadores cotizantes en cuanto a suficiencia y mantenimiento de poder adquisitivo, garantizados por el ordenamiento jur\u00eddico.<\/p>\n<h4>La sostenibilidad del sistema de reparto<\/h4>\n<p style=\"text-align: justify;\">Es indiscutible que el soporte de las pensiones p\u00fablicas son las cotizaciones sociales. Prueba de ello es que, seg\u00fan c\u00e1lculos de CCOO, los super\u00e1vits generados durante decenios por nuestro sistema de reparto, utilizados para sostener la sanidad y otras pol\u00edticas p\u00fablicas, ascienden a 519.104 millones de euros saqueados a la Seguridad Social. Y que podr\u00edan haber nutrido unas reservas suficientes para financiar las carencias actuales en cotizaciones sociales, que ha generado el incremento del paro, las reformas laborales, los bajos salarios y la precariedad.<\/p>\n<p style=\"text-align: justify;\">Con car\u00e1cter subsidiario, la garant\u00eda de la sostenibilidad del sistema de reparto es el Estado con sus recursos propios. Cuando las cotizaciones sean insuficientes, seg\u00fan la Ley General de Seguridad Social (art. 109), el Estado debe realizar aportaciones obligatorias desde su presupuesto al Presupuesto de la Seguridad Social: debe financiar con aportaciones estatales, no con pr\u00e9stamos reembolsables. De esta manera se garantiza el derecho de los trabajadores jubilados a cobrar su pensi\u00f3n, derecho cuya garant\u00eda de cumplimiento tiene rango constitucional (art. 41 y 50).<\/p>\n<p style=\"text-align: justify;\">La concesi\u00f3n de cr\u00e9ditos para financiar desequilibrios entre cotizaciones y gastos de la Seguridad Social han formado una falsa deuda de la Seguridad Social con Estado de 17.168,65 millones de euros generada de 1992 a 1999. En su momento Pedro D\u00edaz Chavero, de UGT, denunci\u00f3 que con la concesi\u00f3n de pr\u00e9stamos en vez de aportaciones \u00ab<strong><em>en la pr\u00e1ctica lo que se produc\u00eda era una transferencia de d\u00e9ficit del Estado a la Seguridad Social<\/em><\/strong>\u00ab. La concesi\u00f3n este a\u00f1o de una cr\u00e9dito similar por 10.192 millones de euros ha hecho reclamar a CCOO y UGT que \u00ab<strong><em>las pensiones se garanticen con aportaciones del Estado y no con pr\u00e9stamos\u00bb<\/em><\/strong>. Siempre puede el gobierno poner esas deudas al cobro, como hace ahora en el Pacto de Toledo, que a escondidas pretende cancelarlas a cambio de los edificios sanitarios propiedad de la Seguridad Social y registrados a nombre de la Tesorer\u00eda General de la Seguridad Social, pues su adquisici\u00f3n se financi\u00f3 con cotizaciones. Intentar cobrar esa deuda en vez de condonarla, que es lo establecido por las auditor\u00edas p\u00fablicas, supondr\u00e1, caso de adoptarse, un nuevo saqueo al patrimonio de la Seguridad Social.<\/p>\n<h4>Las propuestas de las organizaciones obreras para la sostenibilidad del sistema<\/h4>\n<p style=\"text-align: justify;\">Las propuestas de las organizaciones obreras no ponen en el centro la exigencia, con todas sus consecuencias, del cumplimento de la obligaci\u00f3n del gobierno de financiar con aportaciones del Estado las necesidades de la Seguridad Social, aceptan las restricciones impuestas por el d\u00e9ficit del Estado acordado con la UE y se desv\u00edan hacia la creaci\u00f3n de impuestos finalistas con los que completar los recursos necesarios para el pago de las pensiones. El PSOE con \u00ab<strong><em>una nueva figura impositiva que tendr\u00e1 car\u00e1cter finalista y vinculada a la financiaci\u00f3n de las pensiones<\/em>\u00ab<\/strong>, IU con \u00ab<strong><em>la financiaci\u00f3n progresiva en los PGE <\/em><\/strong>(sic)<strong><em> de las prestaciones por muerte o supervivencia\u00bb<\/em><\/strong>. Los sindicatos se pronuncian igualmente por la creaci\u00f3n de nuevas fuentes de financiaci\u00f3n vinculadas a los impuestos, es m\u00e1s, UGT y CCOO incluso preparan movilizaciones en defensa de las pensiones a finales de septiembre y entre sus \u00abexigencias\u00bb se dice que la financiaci\u00f3n suficiente del sistema de Seguridad Social \u00ab<strong><em>debe estar basada en impuestos finalistas y totalmente formalizados<\/em><\/strong>\u00ab.<\/p>\n<p style=\"text-align: justify;\">Estas propuestas, sin justificaci\u00f3n financiera alguna dada la obligaci\u00f3n estatal de aporta recursos en caso de desequilibrios, tienen una l\u00f3gica que conduce a un cambio de modelo del actual sistema de reparto, que, desnaturalizado, estar\u00eda sometido a los vaivenes de la pol\u00edtica econ\u00f3mica de los gobiernos y ver\u00eda debilitado su anclaje en la acci\u00f3n de la clase obrera, los salarios y la acci\u00f3n sindical.<\/p>\n<h4>La proposici\u00f3n de ley de Podemos: \u00bfun puente hacia el cambio de modelo?<\/h4>\n<p style=\"text-align: justify;\">El mi\u00e9rcoles 5 de julio Podemos present\u00f3 una Proposici\u00f3n de Ley (PL) sobre reforma de las pensiones que, de ser aprobada, derogar\u00eda los aspectos m\u00e1s lacerantes de las reformas de 2011 y de 2013. En caso de no aprobarse la derogaci\u00f3n de ambas reformas anuncian los dirigentes de Podemos su determinaci\u00f3n de abandonar el Pacto de Toledo.<\/p>\n<p style=\"text-align: justify;\">Muy acertadamente el Proyecto de Ley denuncia que <strong><em>\u00abla baja recaudaci\u00f3n de cotizaciones no se compensa con aportes de los Presupuestos del Estado, con suficientes aportaciones estatales\u00bb<\/em><\/strong>, seg\u00fan lo establecido legalmente. Pero contradictoriamente, introduce en su texto un puente hacia los partidarios del cambio del modelo actual de Seguridad Social cuando se\u00f1ala como v\u00eda de incremento de los recursos <strong><em>\u00abla creaci\u00f3n de impuestos finalistas (por aumento demogr\u00e1fico, o contribuci\u00f3n de solidaridad) para cubrir los d\u00e9ficits de la financiaci\u00f3n contributiva, como se ha introducido en otros pa\u00edses, o un IVA social\u00bb.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">En principio, la Proposici\u00f3n de Ley, para superar los vetos ya habituales del Gobierno minoritario de Rajoy, y para su tramitaci\u00f3n y aprobaci\u00f3n, podr\u00eda ser la base de la unidad de todos los que defienden las pensiones y rechazan el cambio del actual modelo de Seguridad Social, e incluso podr\u00eda ser punto de arranque la movilizaci\u00f3n contra el gobierno. Pero esa lucha por la unidad en defensa de las pensiones y contra Rajoy se puede ver debilitada por la puerta que se abre en la propia Proposici\u00f3n de Ley a la eventual financiaci\u00f3n por impuestos finalistas o IVA.<\/p>\n<p style=\"text-align: justify;\">El sistema actual de reparto es s\u00f3lido y solvente y su garant\u00eda reposa en la acci\u00f3n de la clase obrera en su lucha por los salarios, fuente de las cotizaciones sociales, y en la obligaci\u00f3n del gobierno de hacer las aportaciones necesarias para cubrir las carencias de cotizaciones que su pol\u00edtica genera. Los riesgos del sistema vienen de la acci\u00f3n del gobierno, de las reformas de 2011 y 2013, que, de no derogarse, reducir\u00eda las pensiones a niveles asistenciales.<\/p>\n<p style=\"text-align: justify;\">Frente a esta situaci\u00f3n de incertidumbre solo la acci\u00f3n de la clase obrera y sus organizaciones puede enderezar la situaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Cada vez se manifiesta con m\u00e1s fuerza la urgente necesidad de coordinar la lucha por la unidad de las organizaciones obreras por la derogaci\u00f3n de la reformas, contra el cambio de modelo de la financiaci\u00f3n por impuestos finalistas y a favor de reforzar los mecanismos de las solidaridad obrera del sistema de reparto en base al cual los trabajadores activos pagan con su salario diferido la pensi\u00f3n de los trabajadores jubilados.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La comisi\u00f3n del Pacto de Toledo ten\u00eda previsto resolver con prontitud las propuestas de reformas del actual sistema de pensiones. Las necesidades derivadas de la debilidad del gobierno minoritario de Rajoy exig\u00edan cerrar lo antes posible la discusi\u00f3n sobre las pensiones<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[61],"tags":[88,66,687,672,843,376],"class_list":["post-2837","post","type-post","status-publish","format-standard","hentry","category-cartas","tag-pensiones","tag-rajoy","tag-reforma-de-las-pensiones","tag-seguridad-social","tag-sistema-de-reparto","tag-zapatero"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"La comisi\u00f3n del Pacto de Toledo ten\u00eda previsto resolver con prontitud las propuestas de reformas del actual sistema de pensiones\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"keywords\" content=\"pensiones,rajoy,reforma de las pensiones,seguridad social,sistema de reparto,zapatero,cartas\" \/>\n\t<link rel=\"canonical\" href=\"http:\/\/posicuarta.org\/cartasblog\/pensiones-en-defensa-del-actual-sistema-de-reparto\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Carta Semanal | Todas las semanas el POSI publica esta carta sobre temas de actualidad\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Pensiones: en defensa del actual sistema de reparto | Carta Semanal\" \/>\n\t\t<meta property=\"og:description\" content=\"La comisi\u00f3n del Pacto de Toledo ten\u00eda previsto resolver con prontitud las propuestas de reformas del actual sistema de pensiones\" \/>\n\t\t<meta property=\"og:url\" content=\"http:\/\/posicuarta.org\/cartasblog\/pensiones-en-defensa-del-actual-sistema-de-reparto\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-07-17T10:16:46+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-07-17T10:16:46+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Pensiones: en defensa del actual sistema de reparto | Carta Semanal\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La comisi\u00f3n del Pacto de Toledo ten\u00eda previsto resolver con prontitud las propuestas de reformas del actual sistema de pensiones\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/pensiones-en-defensa-del-actual-sistema-de-reparto\\\/#article\",\"name\":\"Pensiones: en defensa del actual sistema de reparto | Carta Semanal\",\"headline\":\"Pensiones: en defensa del actual sistema de reparto\",\"author\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Carta-636.jpg\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/pensiones-en-defensa-del-actual-sistema-de-reparto\\\/#articleImage\",\"width\":419,\"height\":600},\"datePublished\":\"2017-07-17T12:16:46+02:00\",\"dateModified\":\"2017-07-17T12:16:46+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/pensiones-en-defensa-del-actual-sistema-de-reparto\\\/#webpage\"},\"isPartOf\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/pensiones-en-defensa-del-actual-sistema-de-reparto\\\/#webpage\"},\"articleSection\":\"Cartas, pensiones, Rajoy, reforma de las pensiones, Seguridad Social, sistema de reparto, Zapatero\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/pensiones-en-defensa-del-actual-sistema-de-reparto\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/category\\\/cartas\\\/#listItem\",\"name\":\"Cartas\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/category\\\/cartas\\\/#listItem\",\"position\":2,\"name\":\"Cartas\",\"item\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/category\\\/cartas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/pensiones-en-defensa-del-actual-sistema-de-reparto\\\/#listItem\",\"name\":\"Pensiones: en defensa del actual sistema de reparto\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/pensiones-en-defensa-del-actual-sistema-de-reparto\\\/#listItem\",\"position\":3,\"name\":\"Pensiones: en defensa del actual sistema de reparto\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/category\\\/cartas\\\/#listItem\",\"name\":\"Cartas\"}}]},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#organization\",\"name\":\"Carta Semanal\",\"description\":\"Todas las semanas el POSI publica esta carta sobre temas de actualidad\",\"url\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/author\\\/admin\\\/#author\",\"url\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/pensiones-en-defensa-del-actual-sistema-de-reparto\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5f86a8150e0ed923470fca03ba20c51f6a89fd5b70e7b345283c4b0866a65ab?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/pensiones-en-defensa-del-actual-sistema-de-reparto\\\/#webpage\",\"url\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/pensiones-en-defensa-del-actual-sistema-de-reparto\\\/\",\"name\":\"Pensiones: en defensa del actual sistema de reparto | Carta Semanal\",\"description\":\"La comisi\\u00f3n del Pacto de Toledo ten\\u00eda previsto resolver con prontitud las propuestas de reformas del actual sistema de pensiones\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/pensiones-en-defensa-del-actual-sistema-de-reparto\\\/#breadcrumblist\"},\"author\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2017-07-17T12:16:46+02:00\",\"dateModified\":\"2017-07-17T12:16:46+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#website\",\"url\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/\",\"name\":\"Carta Semanal\",\"description\":\"Todas las semanas el POSI publica esta carta sobre temas de actualidad\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Pensiones: en defensa del actual sistema de reparto | Carta Semanal","description":"La comisi\u00f3n del Pacto de Toledo ten\u00eda previsto resolver con prontitud las propuestas de reformas del actual sistema de pensiones","canonical_url":"http:\/\/posicuarta.org\/cartasblog\/pensiones-en-defensa-del-actual-sistema-de-reparto\/","robots":"max-image-preview:large","keywords":"pensiones,rajoy,reforma de las pensiones,seguridad social,sistema de reparto,zapatero,cartas","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/posicuarta.org\/cartasblog\/pensiones-en-defensa-del-actual-sistema-de-reparto\/#article","name":"Pensiones: en defensa del actual sistema de reparto | Carta Semanal","headline":"Pensiones: en defensa del actual sistema de reparto","author":{"@id":"http:\/\/posicuarta.org\/cartasblog\/author\/admin\/#author"},"publisher":{"@id":"http:\/\/posicuarta.org\/cartasblog\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/posicuarta.org\/cartasblog\/wp-content\/uploads\/2017\/07\/Carta-636.jpg","@id":"http:\/\/posicuarta.org\/cartasblog\/pensiones-en-defensa-del-actual-sistema-de-reparto\/#articleImage","width":419,"height":600},"datePublished":"2017-07-17T12:16:46+02:00","dateModified":"2017-07-17T12:16:46+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"http:\/\/posicuarta.org\/cartasblog\/pensiones-en-defensa-del-actual-sistema-de-reparto\/#webpage"},"isPartOf":{"@id":"http:\/\/posicuarta.org\/cartasblog\/pensiones-en-defensa-del-actual-sistema-de-reparto\/#webpage"},"articleSection":"Cartas, pensiones, Rajoy, reforma de las pensiones, Seguridad Social, sistema de reparto, Zapatero"},{"@type":"BreadcrumbList","@id":"http:\/\/posicuarta.org\/cartasblog\/pensiones-en-defensa-del-actual-sistema-de-reparto\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog#listItem","position":1,"name":"Home","item":"http:\/\/posicuarta.org\/cartasblog","nextItem":{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog\/category\/cartas\/#listItem","name":"Cartas"}},{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog\/category\/cartas\/#listItem","position":2,"name":"Cartas","item":"http:\/\/posicuarta.org\/cartasblog\/category\/cartas\/","nextItem":{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog\/pensiones-en-defensa-del-actual-sistema-de-reparto\/#listItem","name":"Pensiones: en defensa del actual sistema de reparto"},"previousItem":{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog#listItem","name":"Home"}},{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog\/pensiones-en-defensa-del-actual-sistema-de-reparto\/#listItem","position":3,"name":"Pensiones: en defensa del actual sistema de reparto","previousItem":{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog\/category\/cartas\/#listItem","name":"Cartas"}}]},{"@type":"Organization","@id":"http:\/\/posicuarta.org\/cartasblog\/#organization","name":"Carta Semanal","description":"Todas las semanas el POSI publica esta carta sobre temas de actualidad","url":"http:\/\/posicuarta.org\/cartasblog\/"},{"@type":"Person","@id":"http:\/\/posicuarta.org\/cartasblog\/author\/admin\/#author","url":"http:\/\/posicuarta.org\/cartasblog\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"http:\/\/posicuarta.org\/cartasblog\/pensiones-en-defensa-del-actual-sistema-de-reparto\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/e5f86a8150e0ed923470fca03ba20c51f6a89fd5b70e7b345283c4b0866a65ab?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"http:\/\/posicuarta.org\/cartasblog\/pensiones-en-defensa-del-actual-sistema-de-reparto\/#webpage","url":"http:\/\/posicuarta.org\/cartasblog\/pensiones-en-defensa-del-actual-sistema-de-reparto\/","name":"Pensiones: en defensa del actual sistema de reparto | Carta Semanal","description":"La comisi\u00f3n del Pacto de Toledo ten\u00eda previsto resolver con prontitud las propuestas de reformas del actual sistema de pensiones","inLanguage":"es-ES","isPartOf":{"@id":"http:\/\/posicuarta.org\/cartasblog\/#website"},"breadcrumb":{"@id":"http:\/\/posicuarta.org\/cartasblog\/pensiones-en-defensa-del-actual-sistema-de-reparto\/#breadcrumblist"},"author":{"@id":"http:\/\/posicuarta.org\/cartasblog\/author\/admin\/#author"},"creator":{"@id":"http:\/\/posicuarta.org\/cartasblog\/author\/admin\/#author"},"datePublished":"2017-07-17T12:16:46+02:00","dateModified":"2017-07-17T12:16:46+02:00"},{"@type":"WebSite","@id":"http:\/\/posicuarta.org\/cartasblog\/#website","url":"http:\/\/posicuarta.org\/cartasblog\/","name":"Carta Semanal","description":"Todas las semanas el POSI publica esta carta sobre temas de actualidad","inLanguage":"es-ES","publisher":{"@id":"http:\/\/posicuarta.org\/cartasblog\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Carta Semanal | Todas las semanas el POSI publica esta carta sobre temas de actualidad","og:type":"article","og:title":"Pensiones: en defensa del actual sistema de reparto | Carta Semanal","og:description":"La comisi\u00f3n del Pacto de Toledo ten\u00eda previsto resolver con prontitud las propuestas de reformas del actual sistema de pensiones","og:url":"http:\/\/posicuarta.org\/cartasblog\/pensiones-en-defensa-del-actual-sistema-de-reparto\/","article:published_time":"2017-07-17T10:16:46+00:00","article:modified_time":"2017-07-17T10:16:46+00:00","twitter:card":"summary","twitter:title":"Pensiones: en defensa del actual sistema de reparto | Carta Semanal","twitter:description":"La comisi\u00f3n del Pacto de Toledo ten\u00eda previsto resolver con prontitud las propuestas de reformas del actual sistema de pensiones"},"aioseo_meta_data":{"post_id":"2837","title":null,"description":"La comisi\u00f3n del Pacto de Toledo ten\u00eda previsto resolver con prontitud las propuestas de reformas del actual sistema de pensiones","keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-15 19:14:35","updated":"2025-07-01 14:09:49","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/posicuarta.org\/cartasblog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/posicuarta.org\/cartasblog\/category\/cartas\/\" title=\"Cartas\">Cartas<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPensiones: en defensa del actual sistema de reparto\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"http:\/\/posicuarta.org\/cartasblog"},{"label":"Cartas","link":"http:\/\/posicuarta.org\/cartasblog\/category\/cartas\/"},{"label":"Pensiones: en defensa del actual sistema de reparto","link":"http:\/\/posicuarta.org\/cartasblog\/pensiones-en-defensa-del-actual-sistema-de-reparto\/"}],"_links":{"self":[{"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/posts\/2837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/comments?post=2837"}],"version-history":[{"count":6,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/posts\/2837\/revisions"}],"predecessor-version":[{"id":2844,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/posts\/2837\/revisions\/2844"}],"wp:attachment":[{"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/media?parent=2837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/categories?post=2837"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/tags?post=2837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}