{"id":6060,"date":"2021-10-11T18:33:49","date_gmt":"2021-10-11T16:33:49","guid":{"rendered":"http:\/\/posicuarta.org\/cartasblog\/?p=6060"},"modified":"2025-12-09T16:21:51","modified_gmt":"2025-12-09T14:21:51","slug":"se-cierra-un-periodo-se-abre-uno-nuevo","status":"publish","type":"post","link":"http:\/\/posicuarta.org\/cartasblog\/se-cierra-un-periodo-se-abre-uno-nuevo\/","title":{"rendered":"\u00abSe cierra un periodo, se abre uno nuevo&#8230;\u00bb"},"content":{"rendered":"<h3><a href=\"http:\/\/posicuarta.org\/cartasblog\/es-tanca-un-periode-sobre-un-de-nou\/\">Carta Semanal 856 en catal\u00e1n<\/a><\/h3>\n<h3><a href=\"http:\/\/posicuarta.org\/cartasblog\/wp-content\/uploads\/2021\/10\/Carta_856.pdf\">Carta Semanal 856 para descargar en PDF<\/a><\/h3>\n<h2 style=\"text-align: justify;\"><strong><a href=\"http:\/\/posicuarta.org\/cartasblog\/wp-content\/uploads\/2021\/10\/Carta_856.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-6069\" src=\"http:\/\/posicuarta.org\/cartasblog\/wp-content\/uploads\/2021\/10\/Carta_856.jpg\" alt=\"\" width=\"150\" height=\"212\" srcset=\"http:\/\/posicuarta.org\/cartasblog\/wp-content\/uploads\/2021\/10\/Carta_856.jpg 595w, http:\/\/posicuarta.org\/cartasblog\/wp-content\/uploads\/2021\/10\/Carta_856-212x300.jpg 212w, http:\/\/posicuarta.org\/cartasblog\/wp-content\/uploads\/2021\/10\/Carta_856-106x150.jpg 106w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Esta semana se publica en espa\u00f1ol el n\u00famero 109 de <em>La Verdad<\/em>. Esta Carta Semanal proporciona un resumen de su contenido para preparar su difusi\u00f3n y su discusi\u00f3n. El t\u00edtulo de la portada presenta su contenido: \u00abSe cierra un periodo, se abre uno nuevo\u2026 (notas del Secretariado de la IV Internacional); Dosier: Transici\u00f3n ecol\u00f3gica y econom\u00eda \u00abverde\u00bb.<\/strong><\/h2>\n<p><!--more--><\/p>\n<h3><strong>PRIMERAS NOTAS DEL SECRETARIADO INTERNACIONAL PREPARATORIAS DE LA DISCUSI\u00d3N DEL X CONGRESO MUNDIAL DE LA IV INTERNACIONAL<\/strong><\/h3>\n<p style=\"text-align: justify;\">Estas notas del Secretariado internacional tienen por objeto alimentar la discusi\u00f3n de las secciones. Hay que asimilar plenamente los grandes cambios.<\/p>\n<p style=\"text-align: justify;\">Para comprender el alcance de la retirada de las tropas americanas de Kabul, hay que enlazarlo con la carta dirigida el 8 de septiembre por Janet Yellen, secretaria de Estado del Tesoro, a los congresistas. En ella les exhorta a que eliminen el l\u00edmite de la deuda. Cualquier retraso, dice, situar\u00eda \u00aba los Estados Unidos en la incapacidad de cumplir con sus obligaciones por primera vez en su historia [y] causar\u00eda un da\u00f1o irreparable a la econom\u00eda de Estados Unidos y a los mercados financieros globales\u00bb. Dif\u00edcil decir con m\u00e1s claridad que la decisi\u00f3n estadounidense de desentenderse no se limita a un ajuste de orden militar del ejercito norteamericano, sino que constituye una clar\u00edsima expresi\u00f3n de la crisis de todo el sistema de dominaci\u00f3n imperialista. Imposible aislarlo del giro del mundo y de su devastaci\u00f3n por las bandas de los monopolios imperialistas. \u00abNueve millones de personas mueren de hambre cada a\u00f1o en el mundo; el n\u00famero de refugiados expulsados de sus tierras por la guerra y la miseria alcanza la alucinante cifra de 82,4 millones (seg\u00fan el ACNUR).\u00bb<\/p>\n<p style=\"text-align: justify;\">La descomposici\u00f3n del sistema capitalista es el resultado de la dislocaci\u00f3n del mercado mundial provocada por la saturaci\u00f3n de los mercados y la sobreacumulaci\u00f3n. Por otra parte, Joe Biden justific\u00f3 la retirada americana de Kabul para concentrarse en China. Pero la ofensiva ser\u00e1 tambi\u00e9n contra los viejos imperialismos de Europa que deben afrontar los trust americanos.<\/p>\n<p style=\"text-align: justify;\">\u00abFrente a la estrechez del mercado mundial, a la competencia, el imperialismo en crisis debe abrirse nuevos mercados utilizando la cuesti\u00f3n de la ecolog\u00eda -es la pretendida \u00abtransici\u00f3n energ\u00e9tica\u00bb, la \u00abgreen\u00bb econom\u00eda del plan Biden-, arrastrando a escala mundial la liquidaci\u00f3n de ramas enteras de la industria que ya no son rentables. Es una destrucci\u00f3n gigantesca de las fuerzas.<\/p>\n<p style=\"text-align: justify;\">El capital, a fin de contrarrestar el descenso tendencial de la tasa de ganancia, ataca la fuerza de trabajo mediante despidos masivos y eliminaci\u00f3n de derechos y conquistas. Es preciso que todo lo concedido durante decenios (conquistas de 1945 en Europa, las de la independencia en los pa\u00edses dominados) sea irremisiblemente destruido para preservar e \u00aborden mundial\u00bb: c\u00f3digo laboral, pensiones, sanidad, escuelas, servicios p\u00fablicos. Al hacerlo, socava los fundamentos sobre los que se levantaron los Estados burgueses, muy especialmente en Europa.<\/p>\n<p style=\"text-align: justify;\">Con la pandemia este objetivo de los gobiernos pretend\u00eda contrarrestar el punto com\u00fan de las movilizaciones desde 2019 \u00ab\u00a1V\u00e1yanse, Fuera todos!\u00bb. Quieren repetir la misma operaci\u00f3n con la cuesti\u00f3n del clima. Debido al rechazo de los partidos, las colaboraciones de clase de tipo frente popular de los a\u00f1os 30 ya no son posibles, hace falta integrar a todas las fuerzas en el consenso.<\/p>\n<p style=\"text-align: justify;\">\u00abLa IV Internacional y sus secciones no pueden ignorar la combinaci\u00f3n realizada para ayudar a salvar el sistema mediante la ilusi\u00f3n de una utop\u00eda reaccionaria de bien com\u00fan bajo el capitalismo\u00bb. La IV Internacional combate el consenso. Est\u00e1 en contra de la alianza de explotados y explotadores. El consenso es una forma moderna del viejo corporativismo, retocado con colores actuales, que busca destruir las organizaciones sindicales como organizaciones de clase.<\/p>\n<p style=\"text-align: justify;\">Ante la pol\u00edtica de acompa\u00f1amiento de las c\u00fapulas sindicales, se organiza la resistencia. Los militantes quieren reapropiarse de sus organizaciones de clase, se agrupan en torno a puntos de apoyo, combatiendo en defensa de la independencia de clase y de las organizaciones independientes de la clase obrera.<\/p>\n<p style=\"text-align: justify;\">La IV Internacional se mantiene \u00edntegramente en el terreno de la independencia de clase: defensa de la independencia de las organizaciones sindicales y apoyo a todas esas movilizaciones que, partiendo de abajo, se inscriben para nosotros en la perspectiva del combate por crear las formas organizativas controladas por las propias masas a fin de romper la resistencia contrarrevolucionaria de los aparatos.<\/p>\n<p style=\"text-align: justify;\">En esta nueva situaci\u00f3n, en la que todas las relaciones pol\u00edticas est\u00e1n trastocadas, hay que liberarse, apoy\u00e1ndose en el an\u00e1lisis marxista, de los esquemas del pasado. La IV Internacional debe estar atenta a todos esos movimientos e intervenir en ellos para que se sumen al combate general de la clase obrera que plantear\u00e1 necesariamente la cuesti\u00f3n del poder.\u00bb<\/p>\n<p style=\"text-align: justify;\">Nadie puede prever las formas que tomar\u00e1 el per\u00edodo que se abre, pero es una certeza: para su supervivencia, el imperialismo va a desencadenar la barbarie a escala mundial. En ese enfrentamiento entre las clases sociales antagonistas, en cuyo seno deber\u00e1 \u00abprobarse\u00bb e implantarse la IV Internacional, se dibujar\u00e1 el nuevo periodo hist\u00f3rico.<\/p>\n<h3><strong>DOSIER: BIENES COMUNES, TRANSICI\u00d3N ECOL\u00d3GICA Y ENERG\u00c9TICA, ECONOM\u00cdA \u00abVERDE\u00bb\u2026<\/strong><\/h3>\n<p style=\"text-align: justify;\">Para los grandes capitalistas y los gobiernos, la transici\u00f3n ecol\u00f3gica, la econom\u00eda \u00abverde\u00bb es la ocasi\u00f3n de realizar lo que no han podido hacer hasta ahora, es decir, liquidar ramas enteras de la industria, cuestionar las conquistas de 1945 en Europa y la independencia en los pa\u00edses oprimidos. Los diferentes art\u00edculos demuestran la realidad de una operaci\u00f3n de supervivencia del sistema capitalista y sus consecuencias para las poblaciones trabajadoras.<\/p>\n<h3>ENERG\u00cdA E\u00d3LICA, TRANSICI\u00d3N ECOL\u00d3GICA Y CAPITAL<\/h3>\n<p style=\"text-align: justify;\">Esta t\u00e9cnica, que se presenta como una electricidad con baja emisi\u00f3n de carbono, es objeto de un martilleo medi\u00e1tico intensivo. Grandes sumas de dinero (160.000 millones en cinco a\u00f1os en Alemania) est\u00e1n a cargo del contribuyente. En Francia y en Espa\u00f1a, tambi\u00e9n se prev\u00e9n grandes proyectos.<\/p>\n<p style=\"text-align: justify;\">\u00bfCu\u00e1l es realmente el balance de carbono de la turbina e\u00f3lica? Existen estudios serios que demuestran que no es excelente y es mucho peor que el de la hidr\u00e1ulica o la nuclear. En efecto, hay que tener en cuenta la totalidad de la cadena de construcci\u00f3n y de utilizaci\u00f3n, y no un segmento limitado. Son las falsas presentaciones del balance de carbono las que sirven de pretexto para una financiaci\u00f3n masiva.<\/p>\n<p style=\"text-align: justify;\">La creaci\u00f3n de puestos de trabajo anunciados es d\u00e9bil y se utiliza para privatizar y precarizar, destruir el sector p\u00fablico. El ejemplo de Texas muestra los efectos catastr\u00f3ficos de este mecanismo.<\/p>\n<h3>FINANZAS Y ECONOM\u00cdA VERDE<\/h3>\n<p style=\"text-align: justify;\">El eslogan \u00abTodos unidos contra el virus\u00bb deb\u00eda enmascarar el estado desastroso de los sistemas de salud, sometidos a los planes de privatizaci\u00f3n y de austeridad. Tambi\u00e9n deb\u00eda disimular las medidas liberticidas, que deben permitir acelerar la destrucci\u00f3n de las conquistas sociales. En este marco, \u00bfc\u00f3mo valorar la \u00abresoluci\u00f3n verde\u00bb propuesta por la Uni\u00f3n Europea el 14 de julio?<\/p>\n<p style=\"text-align: justify;\">Europa est\u00e1 atrapada en su dependencia de los Estados Unidos, que han decidido salvar su econom\u00eda afectada por una crisis sin precedentes. Toda la industria europea est\u00e1 amenazada.<\/p>\n<p style=\"text-align: justify;\">El plan que se someter\u00e1 a la aprobaci\u00f3n del Consejo Europeo prev\u00e9 doce iniciativas legislativas. Los fondos europeos que se destinar\u00e1n a estos planes est\u00e1n sujetos a una doble condicionalidad: acentuar las destrucciones sociales, liquidar sectores enteros de la producci\u00f3n (ejemplo: los cr\u00e9ditos para Espa\u00f1a condicionados a la reforma laboral).<\/p>\n<p style=\"text-align: justify;\">A la vez que se alaba la creaci\u00f3n de puestos de trabajo, se hace un silencio total sobre la destrucci\u00f3n que estos planes provocar\u00e1n, por ejemplo, en el autom\u00f3vil.<\/p>\n<p style=\"text-align: justify;\">El temor de una explosi\u00f3n social, de resistencias tipo \u00abchalecos amarillos\u00bb, ha llevado a la Comisi\u00f3n Europea a crear un fondo social para el clima de 72.000 millones, que pretende amortiguar tanto como sea posible este desempleo masivo. Los dirigentes de los partidos socialdem\u00f3cratas y exestalinistas han retomado estos objetivos con entusiasmo.<\/p>\n<h3>LA \u00abACTITUD VERDE\u00bb DE LAS MULTINACIONALES<\/h3>\n<p style=\"text-align: justify;\">Las grandes empresas compiten por t\u00e9cnicas de gesti\u00f3n para aumentar la \u00abeficiencia social\u00bb. Se trata de una nueva asociaci\u00f3n capital-trabajo envuelta en el desarrollo sostenible y la calidad de vida de las generaciones futuras. Los sindicatos a veces se prestan a ello en formas disfrazadas. A los que se oponen a ella se les acusa de obstaculizar la protecci\u00f3n de la naturaleza, de oscurantistas, de ser un peligro para el futuro de la especie humana.<\/p>\n<p style=\"text-align: justify;\">Los discursos sobre la responsabilidad social de las empresas no han tenido ninguna traducci\u00f3n concreta en materia de protecci\u00f3n del medio ambiente. Han representado una nueva forma de hipocres\u00eda dictada por la marcha al caos y el enga\u00f1o del reverdecimiento.<\/p>\n<h3>LA HUELLA ENERG\u00c9TICA DE LA TECNOLOG\u00cdA DIGITAL Y DE LAS \u00abTECNOLOG\u00cdAS VERDES\u00bb<\/h3>\n<p style=\"text-align: justify;\">\u00abLa transici\u00f3n energ\u00e9tica y digital devastar\u00e1 la regi\u00f3n en proporciones sin precedentes.\u00bb Es la constataci\u00f3n del autor del libro <em>La guerra de los metales raros<\/em> aparecido en 2018.<\/p>\n<p style=\"text-align: justify;\">Se dan cifras precisas sobre la creciente demanda de metales raros, la huella de carbono digital. Las tecnolog\u00edas llamadas \u00abverdes\u00bb (turbinas e\u00f3licas, solares, coches el\u00e9ctricos) son muy consumidoras de estos metales.<\/p>\n<p style=\"text-align: justify;\">\u00abTenemos que extraer del subsuelo m\u00e1s metales de los que ha extra\u00eddo la humanidad desde su origen.\u00bb Tambi\u00e9n se necesitan grandes cantidades de agua. Dondequiera que sea posible, el imperialismo americano trata de controlar el abastecimiento, se emprende una reorganizaci\u00f3n generalizada.<\/p>\n<h3>LA ESTRECHEZ DEL MERCADO MUNDIAL Y EL CALLEJ\u00d3N SIN SALIDA DE UNA SUPUESTA \u00abTRANSICI\u00d3N ECOL\u00d3GICA\u00bb<\/h3>\n<p style=\"text-align: justify;\">Hay una propaganda orquestada para decirnos que los \u00abpaquetes de est\u00edmulo\u00bb traer\u00e1n la prosperidad. \u00bfCu\u00e1l es la causa de los crecientes problemas sociales? El art\u00edculo vuelve sobre esta cuesti\u00f3n. \u00bfPor qu\u00e9 el mercado mundial es demasiado estrecho? Marx ha dado una explicaci\u00f3n muy amplia. \u00bfSigue siendo v\u00e1lida?<\/p>\n<p style=\"text-align: justify;\">La guerra comercial y la deuda son mecanismos permanentes del funcionamiento del capital que debe vender para realizar sus beneficios. La guerra comercial se exacerba para eliminar a los competidores y mantener su cuota de mercado. Desde la decisi\u00f3n de agosto de 1971, el imperialismo americano ha utilizado hasta sus l\u00edmites el endeudamiento, el parasitismo, el militarismo.<\/p>\n<p style=\"text-align: justify;\">La transici\u00f3n ecol\u00f3gica se pone de relieve porque el imperialismo, que destruye cada vez m\u00e1s r\u00e1pidamente el medio natural, debe suscitar la ilusi\u00f3n de una transici\u00f3n ecol\u00f3gica para dar la impresi\u00f3n de que el capitalismo puede resolver los problemas y desarrollar un nuevo campo de saqueo y acumulaci\u00f3n con el militarismo y la guerra.<\/p>\n<p style=\"text-align: justify;\">Se trata, pues, de una operaci\u00f3n pol\u00edtica y financiera.<\/p>\n<p style=\"text-align: justify;\">El capitalismo verde es una nueva versi\u00f3n del capitalismo \u00abel mejor, el eterno orden social posible\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carta Semanal 856 en catal\u00e1n Carta Semanal 856 para descargar en PDF Esta semana se publica en espa\u00f1ol el n\u00famero 109 de La Verdad. Esta Carta Semanal proporciona un resumen de su contenido para preparar su difusi\u00f3n y su discusi\u00f3n. El t\u00edtulo de la portada presenta su contenido: \u00abSe cierra un periodo, se abre uno [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[61],"tags":[1130,1126],"class_list":["post-6060","post","type-post","status-publish","format-standard","hentry","category-cartas","tag-cuartainternacional","tag-laverdad"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Carta Semanal 856 en catal\u00e1n Carta Semanal 856 para descargar en PDF Esta semana se publica en espa\u00f1ol el n\u00famero 109 de La Verdad. Esta Carta Semanal proporciona un resumen de su contenido para preparar su difusi\u00f3n y su discusi\u00f3n. El t\u00edtulo de la portada presenta su contenido: \u00abSe cierra un periodo, se abre uno\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"keywords\" content=\"#cuartainternacional,#laverdad,cartas\" \/>\n\t<link rel=\"canonical\" href=\"http:\/\/posicuarta.org\/cartasblog\/se-cierra-un-periodo-se-abre-uno-nuevo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Carta Semanal | Todas las semanas el POSI publica esta carta sobre temas de actualidad\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u00abSe cierra un periodo, se abre uno nuevo\u2026\u00bb | Carta Semanal\" \/>\n\t\t<meta property=\"og:description\" content=\"Carta Semanal 856 en catal\u00e1n Carta Semanal 856 para descargar en PDF Esta semana se publica en espa\u00f1ol el n\u00famero 109 de La Verdad. Esta Carta Semanal proporciona un resumen de su contenido para preparar su difusi\u00f3n y su discusi\u00f3n. El t\u00edtulo de la portada presenta su contenido: \u00abSe cierra un periodo, se abre uno\" \/>\n\t\t<meta property=\"og:url\" content=\"http:\/\/posicuarta.org\/cartasblog\/se-cierra-un-periodo-se-abre-uno-nuevo\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-10-11T16:33:49+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-12-09T14:21:51+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u00abSe cierra un periodo, se abre uno nuevo\u2026\u00bb | Carta Semanal\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Carta Semanal 856 en catal\u00e1n Carta Semanal 856 para descargar en PDF Esta semana se publica en espa\u00f1ol el n\u00famero 109 de La Verdad. Esta Carta Semanal proporciona un resumen de su contenido para preparar su difusi\u00f3n y su discusi\u00f3n. El t\u00edtulo de la portada presenta su contenido: \u00abSe cierra un periodo, se abre uno\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/se-cierra-un-periodo-se-abre-uno-nuevo\\\/#article\",\"name\":\"\\u00abSe cierra un periodo, se abre uno nuevo\\u2026\\u00bb | Carta Semanal\",\"headline\":\"\\u00abSe cierra un periodo, se abre uno nuevo&#8230;\\u00bb\",\"author\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Carta_856.jpg\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/se-cierra-un-periodo-se-abre-uno-nuevo\\\/#articleImage\",\"width\":595,\"height\":841},\"datePublished\":\"2021-10-11T18:33:49+02:00\",\"dateModified\":\"2025-12-09T16:21:51+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/se-cierra-un-periodo-se-abre-uno-nuevo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/se-cierra-un-periodo-se-abre-uno-nuevo\\\/#webpage\"},\"articleSection\":\"Cartas, #cuartainternacional, #laverdad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/se-cierra-un-periodo-se-abre-uno-nuevo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/category\\\/cartas\\\/#listItem\",\"name\":\"Cartas\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/category\\\/cartas\\\/#listItem\",\"position\":2,\"name\":\"Cartas\",\"item\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/category\\\/cartas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/se-cierra-un-periodo-se-abre-uno-nuevo\\\/#listItem\",\"name\":\"\\u00abSe cierra un periodo, se abre uno nuevo&#8230;\\u00bb\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/se-cierra-un-periodo-se-abre-uno-nuevo\\\/#listItem\",\"position\":3,\"name\":\"\\u00abSe cierra un periodo, se abre uno nuevo&#8230;\\u00bb\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/category\\\/cartas\\\/#listItem\",\"name\":\"Cartas\"}}]},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#organization\",\"name\":\"Carta Semanal\",\"description\":\"Todas las semanas el POSI publica esta carta sobre temas de actualidad\",\"url\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/author\\\/admin\\\/#author\",\"url\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/author\\\/admin\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/se-cierra-un-periodo-se-abre-uno-nuevo\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5f86a8150e0ed923470fca03ba20c51f6a89fd5b70e7b345283c4b0866a65ab?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/se-cierra-un-periodo-se-abre-uno-nuevo\\\/#webpage\",\"url\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/se-cierra-un-periodo-se-abre-uno-nuevo\\\/\",\"name\":\"\\u00abSe cierra un periodo, se abre uno nuevo\\u2026\\u00bb | Carta Semanal\",\"description\":\"Carta Semanal 856 en catal\\u00e1n Carta Semanal 856 para descargar en PDF Esta semana se publica en espa\\u00f1ol el n\\u00famero 109 de La Verdad. Esta Carta Semanal proporciona un resumen de su contenido para preparar su difusi\\u00f3n y su discusi\\u00f3n. El t\\u00edtulo de la portada presenta su contenido: \\u00abSe cierra un periodo, se abre uno\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/se-cierra-un-periodo-se-abre-uno-nuevo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/author\\\/admin\\\/#author\"},\"datePublished\":\"2021-10-11T18:33:49+02:00\",\"dateModified\":\"2025-12-09T16:21:51+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#website\",\"url\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/\",\"name\":\"Carta Semanal\",\"description\":\"Todas las semanas el POSI publica esta carta sobre temas de actualidad\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"http:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u00abSe cierra un periodo, se abre uno nuevo\u2026\u00bb | Carta Semanal","description":"Carta Semanal 856 en catal\u00e1n Carta Semanal 856 para descargar en PDF Esta semana se publica en espa\u00f1ol el n\u00famero 109 de La Verdad. Esta Carta Semanal proporciona un resumen de su contenido para preparar su difusi\u00f3n y su discusi\u00f3n. El t\u00edtulo de la portada presenta su contenido: \u00abSe cierra un periodo, se abre uno","canonical_url":"http:\/\/posicuarta.org\/cartasblog\/se-cierra-un-periodo-se-abre-uno-nuevo\/","robots":"max-image-preview:large","keywords":"#cuartainternacional,#laverdad,cartas","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/posicuarta.org\/cartasblog\/se-cierra-un-periodo-se-abre-uno-nuevo\/#article","name":"\u00abSe cierra un periodo, se abre uno nuevo\u2026\u00bb | Carta Semanal","headline":"\u00abSe cierra un periodo, se abre uno nuevo&#8230;\u00bb","author":{"@id":"http:\/\/posicuarta.org\/cartasblog\/author\/admin\/#author"},"publisher":{"@id":"http:\/\/posicuarta.org\/cartasblog\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/posicuarta.org\/cartasblog\/wp-content\/uploads\/2021\/10\/Carta_856.jpg","@id":"http:\/\/posicuarta.org\/cartasblog\/se-cierra-un-periodo-se-abre-uno-nuevo\/#articleImage","width":595,"height":841},"datePublished":"2021-10-11T18:33:49+02:00","dateModified":"2025-12-09T16:21:51+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"http:\/\/posicuarta.org\/cartasblog\/se-cierra-un-periodo-se-abre-uno-nuevo\/#webpage"},"isPartOf":{"@id":"http:\/\/posicuarta.org\/cartasblog\/se-cierra-un-periodo-se-abre-uno-nuevo\/#webpage"},"articleSection":"Cartas, #cuartainternacional, #laverdad"},{"@type":"BreadcrumbList","@id":"http:\/\/posicuarta.org\/cartasblog\/se-cierra-un-periodo-se-abre-uno-nuevo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog#listItem","position":1,"name":"Home","item":"http:\/\/posicuarta.org\/cartasblog","nextItem":{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog\/category\/cartas\/#listItem","name":"Cartas"}},{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog\/category\/cartas\/#listItem","position":2,"name":"Cartas","item":"http:\/\/posicuarta.org\/cartasblog\/category\/cartas\/","nextItem":{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog\/se-cierra-un-periodo-se-abre-uno-nuevo\/#listItem","name":"\u00abSe cierra un periodo, se abre uno nuevo&#8230;\u00bb"},"previousItem":{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog#listItem","name":"Home"}},{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog\/se-cierra-un-periodo-se-abre-uno-nuevo\/#listItem","position":3,"name":"\u00abSe cierra un periodo, se abre uno nuevo&#8230;\u00bb","previousItem":{"@type":"ListItem","@id":"http:\/\/posicuarta.org\/cartasblog\/category\/cartas\/#listItem","name":"Cartas"}}]},{"@type":"Organization","@id":"http:\/\/posicuarta.org\/cartasblog\/#organization","name":"Carta Semanal","description":"Todas las semanas el POSI publica esta carta sobre temas de actualidad","url":"http:\/\/posicuarta.org\/cartasblog\/"},{"@type":"Person","@id":"http:\/\/posicuarta.org\/cartasblog\/author\/admin\/#author","url":"http:\/\/posicuarta.org\/cartasblog\/author\/admin\/","name":"admin","image":{"@type":"ImageObject","@id":"http:\/\/posicuarta.org\/cartasblog\/se-cierra-un-periodo-se-abre-uno-nuevo\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/e5f86a8150e0ed923470fca03ba20c51f6a89fd5b70e7b345283c4b0866a65ab?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"http:\/\/posicuarta.org\/cartasblog\/se-cierra-un-periodo-se-abre-uno-nuevo\/#webpage","url":"http:\/\/posicuarta.org\/cartasblog\/se-cierra-un-periodo-se-abre-uno-nuevo\/","name":"\u00abSe cierra un periodo, se abre uno nuevo\u2026\u00bb | Carta Semanal","description":"Carta Semanal 856 en catal\u00e1n Carta Semanal 856 para descargar en PDF Esta semana se publica en espa\u00f1ol el n\u00famero 109 de La Verdad. Esta Carta Semanal proporciona un resumen de su contenido para preparar su difusi\u00f3n y su discusi\u00f3n. El t\u00edtulo de la portada presenta su contenido: \u00abSe cierra un periodo, se abre uno","inLanguage":"es-ES","isPartOf":{"@id":"http:\/\/posicuarta.org\/cartasblog\/#website"},"breadcrumb":{"@id":"http:\/\/posicuarta.org\/cartasblog\/se-cierra-un-periodo-se-abre-uno-nuevo\/#breadcrumblist"},"author":{"@id":"http:\/\/posicuarta.org\/cartasblog\/author\/admin\/#author"},"creator":{"@id":"http:\/\/posicuarta.org\/cartasblog\/author\/admin\/#author"},"datePublished":"2021-10-11T18:33:49+02:00","dateModified":"2025-12-09T16:21:51+02:00"},{"@type":"WebSite","@id":"http:\/\/posicuarta.org\/cartasblog\/#website","url":"http:\/\/posicuarta.org\/cartasblog\/","name":"Carta Semanal","description":"Todas las semanas el POSI publica esta carta sobre temas de actualidad","inLanguage":"es-ES","publisher":{"@id":"http:\/\/posicuarta.org\/cartasblog\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Carta Semanal | Todas las semanas el POSI publica esta carta sobre temas de actualidad","og:type":"article","og:title":"\u00abSe cierra un periodo, se abre uno nuevo\u2026\u00bb | Carta Semanal","og:description":"Carta Semanal 856 en catal\u00e1n Carta Semanal 856 para descargar en PDF Esta semana se publica en espa\u00f1ol el n\u00famero 109 de La Verdad. Esta Carta Semanal proporciona un resumen de su contenido para preparar su difusi\u00f3n y su discusi\u00f3n. El t\u00edtulo de la portada presenta su contenido: \u00abSe cierra un periodo, se abre uno","og:url":"http:\/\/posicuarta.org\/cartasblog\/se-cierra-un-periodo-se-abre-uno-nuevo\/","article:published_time":"2021-10-11T16:33:49+00:00","article:modified_time":"2025-12-09T14:21:51+00:00","twitter:card":"summary","twitter:title":"\u00abSe cierra un periodo, se abre uno nuevo\u2026\u00bb | Carta Semanal","twitter:description":"Carta Semanal 856 en catal\u00e1n Carta Semanal 856 para descargar en PDF Esta semana se publica en espa\u00f1ol el n\u00famero 109 de La Verdad. Esta Carta Semanal proporciona un resumen de su contenido para preparar su difusi\u00f3n y su discusi\u00f3n. El t\u00edtulo de la portada presenta su contenido: \u00abSe cierra un periodo, se abre uno"},"aioseo_meta_data":{"post_id":"6060","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":{"id":"aioseo-article-634689ed245e8","slug":"article","graphName":"Article","label":"Art\u00edculo","properties":{"type":"BlogPosting","name":"#post_title","headline":"#post_title","description":"#post_excerpt","image":"","keywords":"","author":{"name":"#author_name","url":"#author_url"},"dates":{"include":true,"datePublished":"","dateModified":""}}},"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2021-10-11 16:14:02","updated":"2025-12-09 14:36:49","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/posicuarta.org\/cartasblog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/posicuarta.org\/cartasblog\/category\/cartas\/\" title=\"Cartas\">Cartas<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u00abSe cierra un periodo, se abre uno nuevo\u2026\u00bb\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"http:\/\/posicuarta.org\/cartasblog"},{"label":"Cartas","link":"http:\/\/posicuarta.org\/cartasblog\/category\/cartas\/"},{"label":"\u00abSe cierra un periodo, se abre uno nuevo&#8230;\u00bb","link":"http:\/\/posicuarta.org\/cartasblog\/se-cierra-un-periodo-se-abre-uno-nuevo\/"}],"_links":{"self":[{"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/posts\/6060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/comments?post=6060"}],"version-history":[{"count":9,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/posts\/6060\/revisions"}],"predecessor-version":[{"id":6073,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/posts\/6060\/revisions\/6073"}],"wp:attachment":[{"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/media?parent=6060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/categories?post=6060"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/tags?post=6060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}