{"id":1051,"count":24,"description":"","link":"https:\/\/posicuarta.org\/cartasblog\/tag\/gobierno-de-coalicion\/","name":"gobierno de coalici\u00f3n","slug":"gobierno-de-coalicion","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/posicuarta.org\/cartasblog\/tag\/gobierno-de-coalicion\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/posicuarta.org\\\/cartasblog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/1051\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/posicuarta.org\\\/cartasblog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/posicuarta.org\\\/cartasblog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/posicuarta.org\\\/cartasblog\\\/tag\\\/gobierno-de-coalicion\\\/#listItem\",\"name\":\"gobierno de coalici\\u00f3n\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/posicuarta.org\\\/cartasblog\\\/tag\\\/gobierno-de-coalicion\\\/#listItem\",\"position\":2,\"name\":\"gobierno de coalici\\u00f3n\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/posicuarta.org\\\/cartasblog#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/posicuarta.org\\\/cartasblog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/1051\\\/#collectionpage\",\"url\":\"https:\\\/\\\/posicuarta.org\\\/cartasblog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/1051\\\/\",\"name\":\"gobierno de coalici\\u00f3n | Carta Semanal\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/posicuarta.org\\\/cartasblog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/1051\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#organization\",\"name\":\"Carta Semanal\",\"description\":\"Todas las semanas el POSI publica esta carta sobre temas de actualidad\",\"url\":\"https:\\\/\\\/posicuarta.org\\\/cartasblog\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#website\",\"url\":\"https:\\\/\\\/posicuarta.org\\\/cartasblog\\\/\",\"name\":\"Carta Semanal\",\"description\":\"Todas las semanas el POSI publica esta carta sobre temas de actualidad\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/posicuarta.org\\\/cartasblog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"gobierno de coalici\u00f3n | Carta Semanal","description":"","canonical_url":"https:\/\/posicuarta.org\/cartasblog\/tag\/gobierno-de-coalicion\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/tags\/1051\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/posicuarta.org\/cartasblog#listItem","position":1,"name":"Home","item":"https:\/\/posicuarta.org\/cartasblog","nextItem":{"@type":"ListItem","@id":"https:\/\/posicuarta.org\/cartasblog\/tag\/gobierno-de-coalicion\/#listItem","name":"gobierno de coalici\u00f3n"}},{"@type":"ListItem","@id":"https:\/\/posicuarta.org\/cartasblog\/tag\/gobierno-de-coalicion\/#listItem","position":2,"name":"gobierno de coalici\u00f3n","previousItem":{"@type":"ListItem","@id":"https:\/\/posicuarta.org\/cartasblog#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/tags\/1051\/#collectionpage","url":"https:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/tags\/1051\/","name":"gobierno de coalici\u00f3n | Carta Semanal","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/posicuarta.org\/cartasblog\/#website"},"breadcrumb":{"@id":"https:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/tags\/1051\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/posicuarta.org\/cartasblog\/#organization","name":"Carta Semanal","description":"Todas las semanas el POSI publica esta carta sobre temas de actualidad","url":"https:\/\/posicuarta.org\/cartasblog\/"},{"@type":"WebSite","@id":"https:\/\/posicuarta.org\/cartasblog\/#website","url":"https:\/\/posicuarta.org\/cartasblog\/","name":"Carta Semanal","description":"Todas las semanas el POSI publica esta carta sobre temas de actualidad","inLanguage":"es-ES","publisher":{"@id":"https:\/\/posicuarta.org\/cartasblog\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/posicuarta.org\/cartasblog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tgobierno de coalici\u00f3n\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/posicuarta.org\/cartasblog"},{"label":"gobierno de coalici\u00f3n","link":"https:\/\/posicuarta.org\/cartasblog\/tag\/gobierno-de-coalicion\/"}],"_links":{"self":[{"href":"https:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/tags\/1051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/posicuarta.org\/cartasblog\/wp-json\/wp\/v2\/posts?tags=1051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}